{"id":9743,"date":"2023-05-09T16:00:00","date_gmt":"2023-05-09T20:00:00","guid":{"rendered":"https:\/\/influencias.do\/?p=9743"},"modified":"2023-05-09T16:00:00","modified_gmt":"2023-05-09T20:00:00","slug":"linkedin-anuncia-un-recorte-de-personal-y-ratifica-su-salida-de-china","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/05\/09\/linkedin-anuncia-un-recorte-de-personal-y-ratifica-su-salida-de-china\/","title":{"rendered":"LinkedIn anuncia un recorte de personal y ratifica su salida de China"},"content":{"rendered":"\n<p>La red social de contactos profesionales LinkedIn&nbsp;<a href=\"https:\/\/www.reuters.com\/technology\/linkedin-cut-716-jobs-phase-out-china-local-jobs-app-2023-05-09\/\" target=\"_blank\" rel=\"noreferrer noopener\">anunci\u00f3<\/a>&nbsp;un recorte de personal y su salida gradual del mercado de China. La empresa, propiedad de Microsoft, tiene en la actualidad unos 20.000 empleados.<\/p>\n\n\n\n<p>En total, la compa\u00f1\u00eda prev\u00e9&nbsp;<strong>recortar 716 puestos,<\/strong>&nbsp;con lo que se suma a la ola de despidos en empresas de tecnolog\u00eda que comenz\u00f3 a fines de 2022 y que ya provoc\u00f3 el<strong>&nbsp;cese de unas 190.000 personas&nbsp;<\/strong>en lo que va del a\u00f1o, seg\u00fan&nbsp;<a href=\"https:\/\/layoffs.fyi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Layoffs.fyi<\/a>. En mayo, los trabajos en empresas de tecnolog\u00eda perdidos ascienden a m\u00e1s de 4.500.<\/p>\n\n\n\n<p>Ryan Roslansky, director ejecutivo de LinkedIn, explic\u00f3 en una carta enviada a los trabajadores que ampliar\u00e1n los v\u00ednculos con subcontratistas para atender la demanda de los mercados emergentes.<\/p>\n\n\n\n<p>&#8220;Con el mercado y la demanda de los clientes fluctuando m\u00e1s, y para atender con mayor eficacia a los mercados emergentes y en crecimiento, estamos ampliando el uso de proveedores&#8221;, escribi\u00f3 y agreg\u00f3 que estos proveedores ser\u00e1n &#8220;socios externos&#8221; que asumir\u00edan trabajos nuevos y existentes.<\/p>\n\n\n\n<p>Pese al recorte previsto, Roslansky asegur\u00f3 que estos cambios permitir\u00e1n crear 250 nuevos puestos de empleo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Salida de China<\/h3>\n\n\n\n<p>Otra de las medidas tomadas por la red de contactos profesionales es la de&nbsp;<strong>abandonar China de manera gradual.<\/strong>&nbsp;Tal como hab\u00eda decidido en 2021, avanzar\u00e1 en la salida de su aplicaci\u00f3n, llamada InCareer en el mercado chino, debido a la competencia y a los desaf\u00edos que le plantea el entorno.<\/p>\n\n\n\n<p>&#8220;Pese a nuestro progreso inicial, InCareer enfrent\u00f3 una competencia feroz y un clima macroecon\u00f3mico desafiante, lo que finalmente nos llev\u00f3 a la decisi\u00f3n de descontinuar el servicio&#8221;, aclar\u00f3 la compa\u00f1\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La red social de contactos profesionales LinkedIn&nbsp;anunci\u00f3&nbsp;un recorte de personal y su salida gradual del mercado de China. La empresa, propiedad de Microsoft, tiene en la actualidad unos 20.000 empleados. En total, la compa\u00f1\u00eda prev\u00e9&nbsp;recortar 716 puestos,&nbsp;con lo que se suma a la ola de despidos en empresas de tecnolog\u00eda que comenz\u00f3 a fines de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[2361],"class_list":{"0":"post-9743","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacionales","8":"tag-linkedin"},"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/9743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=9743"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/9743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=9743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=9743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=9743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}