{"id":9514,"date":"2023-05-05T17:00:00","date_gmt":"2023-05-05T21:00:00","guid":{"rendered":"https:\/\/influencias.do\/?p=9514"},"modified":"2023-05-05T17:00:00","modified_gmt":"2023-05-05T21:00:00","slug":"banco-promerica-recibe-reconocimiento-por-iniciativa-de-emision-100-digital-de-tarjetas-de-credito-visa","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/05\/05\/banco-promerica-recibe-reconocimiento-por-iniciativa-de-emision-100-digital-de-tarjetas-de-credito-visa\/","title":{"rendered":"Banco Promerica recibe reconocimiento por iniciativa de emisi\u00f3n 100% digital de tarjetas de cr\u00e9dito Visa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Visa Inc. (NYSE: V), l\u00edder mundial en pagos digitales, otorg\u00f3 un reconocimiento al Banco M\u00faltiple Promerica de la Rep\u00fablica Dominicana por su innovadora iniciativa que lo convierte en la primera entidad bancaria del pa\u00eds en facilitar que usuarios financieros, tanto clientes como no clientes puedan solicitar una tarjeta de cr\u00e9dito Visa de manera 100% digital, obteniendo respuesta inmediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El reconocimiento de Visa para la entidad financiera fue otorgado a Promerica en sus oficinas, donde ejecutivos l\u00edderes de la instituci\u00f3n recibieron una estatuilla para destacar el compromiso y dedicaci\u00f3n del banco al desarrollar una capacidad innovadora que permita que usuarios e interesados puedan obtener una tarjeta Visa Promerica v\u00eda su APP Promerica M\u00f3vil RD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy nos sentimos en Visa muy complacidos de entregar este reconocimiento al Banco M\u00faltiple Promerica por su novedosa iniciativa de facilitar el acceso a no clientes e interesados en obtener una tarjeta de cr\u00e9dito Visa de modo 100% digital\u201d, coment\u00f3 Sofia Antor, gerente general de Visa Rep\u00fablica Dominicana. \u201cEs un paso importante que contribuye a facilitar el acceso a medios de pagos digitales en el pa\u00eds\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Carlos Julio Camilo, presidente ejecutivo de Banco Promerica, indic\u00f3 que es un gran honor para la entidad financiera recibir este reconocimiento de la mano de Visa, empresa l\u00edder mundial en Pagos Digitales. \u201cEste premio reafirma la clara y robusta estrategia de transformaci\u00f3n digital que hemos venido ejecutando en los \u00faltimos a\u00f1os, la cual, nos ha permitido ser un referente en el mercado dominicano con el firme prop\u00f3sito de entregar soluciones cercanas, innovadoras y \u00e1giles\u201d, indic\u00f3 Camilo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el nuevo proceso de solicitud y aprobaci\u00f3n de Tarjetas de Cr\u00e9dito de forma digital, Promerica contin\u00faa destac\u00e1ndose en su propuesta de Medios de Pago, siendo el \u00fanico banco con alianzas con 3 aerol\u00edneas: Spirit, Copa e Iberia. As\u00ed mismo en permitir el uso de sus Tarjetas Visa a trav\u00e9s de su billetera Promerica Pay, permitiendo a los clientes la realizaci\u00f3n de pagos digitales desde el celular y relojes inteligentes sin necesidad de utilizar la tarjeta f\u00edsica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visa Inc. (NYSE: V), l\u00edder mundial en pagos digitales, otorg\u00f3 un reconocimiento al Banco M\u00faltiple Promerica de la Rep\u00fablica Dominicana por su innovadora iniciativa que lo convierte en la primera entidad bancaria del pa\u00eds en facilitar que usuarios financieros, tanto clientes como no clientes puedan solicitar una tarjeta de cr\u00e9dito Visa de manera 100% digital, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-9514","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/9514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=9514"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/9514\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=9514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=9514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=9514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}