{"id":8070,"date":"2023-04-17T09:04:23","date_gmt":"2023-04-17T13:04:23","guid":{"rendered":"https:\/\/influencias.do\/?p=8070"},"modified":"2023-04-17T09:04:23","modified_gmt":"2023-04-17T13:04:23","slug":"el-psoe-y-el-pp-pactan-las-primeras-correcciones-de-la-ley-del-solo-si-es-si","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/04\/17\/el-psoe-y-el-pp-pactan-las-primeras-correcciones-de-la-ley-del-solo-si-es-si\/","title":{"rendered":"El PSOE y el PP pactan las primeras correcciones de la ley del solo s\u00ed es s\u00ed"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El PP y el PSOE han alcanzado un acuerdo este lunes para corregir algunos aspectos de reforma de la ley del solo s\u00ed es s\u00ed, unas modificaciones que seg\u00fan los socialistas son \u201ct\u00e9cnicas\u201d, aunque para los populares \u201ctienen much\u00edsima importancia\u201d, seg\u00fan ha manifestado ambos grupos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los socios de investidura de Pedro S\u00e1nchez, son cambios \u201cdecepcionantes\u201d, en palabras de la diputada de ERC Pilar Valluguera tras concluir la ponencia reunida en el Congreso, que ha aprobado el dictamen de la reforma con los votos del PSOE, PP, Ciudadanos y PNV y la oposici\u00f3n de Vox, Unidas Podemos, ERC y EH-Bildu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La proposici\u00f3n de ley impulsada por los socialistas tras la sucesi\u00f3n de rebajas de condenas a agresores sexuales y que ha dividido a la coalici\u00f3n de gobierno ser\u00e1 debatida este martes en la Comisi\u00f3n de Justicia y llegar\u00e1 al pleno el jueves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan han informado fuentes del grupo popular, los dos principales partidos de la C\u00e1mara han consensuado una enmienda transaccional que vuelve a castigar la distribuci\u00f3n de contenidos que inciten a cometer agresiones sexuales a menores de 16 a\u00f1os, que hab\u00eda quedado destipificado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de este punto, la ponencia solo ha incluido en su dictamen otras dos enmiendas transaccionales consensuadas por PSOE y PP, y dos propuestas m\u00e1s de los populares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre estas modificaciones est\u00e1 la eliminaci\u00f3n de un conector en el segundo p\u00e1rrafo del art\u00edculo 178 de la ley -el que define el delito de agresi\u00f3n sexual- o el cambio de la palabra \u201ccircunstancias\u201d por \u201cmodalidades\u201d para hacer referencia a los diferentes escenarios que pueden darse en una agresi\u00f3n sexual, como la existencia de violencia o anulaci\u00f3n de la voluntad de la v\u00edctima.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-enmiendas-de-caracter-tecnico-segun-el-psoe\">Enmiendas de \u201ccar\u00e1cter t\u00e9cnico\u201d, seg\u00fan el PSOE<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A la salida de la reuni\u00f3n, la secretaria de Igualdad del PSOE, Andrea Fern\u00e1ndez, ha asegurado que todas las enmiendas incluidas son de \u201ccar\u00e1cter t\u00e9cnico\u201d y tienen que ver \u201ccon cuestiones de redacci\u00f3n\u201d, por lo que no modifican \u201csustancialmente\u201d la reforma propuesta por los socialistas ni la definici\u00f3n de consentimiento, que \u201cno se toca ni en un coma\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cModificar simplemente una palabra, una coma o un p\u00e1rrafo ya supone que tenga consecuencias en la propia comprensi\u00f3n del texto\u201d, ha subrayado por su parte la diputada del PP Marta Gonz\u00e1lez, quien ha considerado que \u201chablar exclusivamente de tecnicismos no es muy correcto\u201d porque \u201ca\u00fan siendo tecnicismos, tienen significado y gran importancia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mikel Legarda, diputado del PNV, coincide con los socialistas en que las enmiendas aceptadas \u201cson cuestiones muy t\u00e9cnicas que no afectan al fondo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, ha advertido que la negociaci\u00f3n seguir\u00e1 a lo largo del d\u00eda de hoy para evaluar enmiendas de los otros grupos que no han sido admitidas, como la propuesta de M\u00e1s Pa\u00eds y JxCat para corregir un error de la ley de protecci\u00f3n a la infancia respecto a la prescripci\u00f3n de los delitos contra la libertad del menor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No opinan igual los socios de investidura de Pedro S\u00e1nchez, quienes han calificado el acuerdo de PP y PSOE de \u201cmuy decepcionante\u201d. \u201cEllos sabr\u00e1n lo que hacen pero para las mujeres no es una buena noticia\u201d, ha lamentado Valluguera en declaraciones a los medios junto a la diputada de EH-Bildu Isabel Pozueta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este pacto tampoco es una buena noticia para Unidas Podemos, formaci\u00f3n que ha lamentado que en el texto que ma\u00f1ana se debatir\u00e1 en la Comisi\u00f3n de Justicia no se haya incluido ninguna enmienda del resto de formaciones, algo que, a su parecer, tiene un fondo pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre esto, Fern\u00e1ndez ha resaltado que el PSOE habla con los grupos que les permiten mantener su posici\u00f3n \u201cde la manera m\u00e1s pura posible\u201d porque consideran que su propuesta \u201ces la mejor manera de solucionar el problema ocasionado\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pp-avisa-de-que-queda-negociacion-sobre-el-solo-si-es-si-puede-pasar-de-todo\">PP avisa de que queda negociaci\u00f3n sobre el solo s\u00ed es s\u00ed: Puede pasar de todo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tras acordar hoy el PP y el PSOE las primeras correcciones de la reforma de la ley del solo s\u00ed es s\u00ed, el portavoz de campa\u00f1a del PP, Borja S\u00e9mper, ha se\u00f1alado que \u201cqueda materia todav\u00eda que acordar\u201d y hay negociaci\u00f3n \u201cabierta\u201d hasta el jueves por lo que \u201cpuede pasar de todo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En rueda de prensa tras el Comit\u00e9 de Direcci\u00f3n del PP, S\u00e9mper ha apuntado que hay una serie de \u201cflecos\u201d que acordar antes del jueves, cuando el pleno del Congreso de los Diputados votar\u00e1 la proposici\u00f3n de ley de los socialistas para corregir las menores penas a agresores sexuales que ha conllevado la norma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Preguntado sobre si hay posibilidad de que el PP no vote a favor, S\u00e9mper ha dicho en rueda de prensa que espera que no, aunque si no se garantiza la seguridad jur\u00eddica \u201ctodo es posible\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo querr\u00edamos vernos semanas o meses despu\u00e9s con una chapuza no resuelta, no vamos a ser colaboradores necesarios de m\u00e1s chapuzas\u201d, ha recalcado el dirigente del PP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En todo caso, aunque lo que queda pendiente \u201cno son cuestiones menores\u201d, s\u00ed lo son respecto a las penas, pues para el PP la m\u00e1xima es \u201cvolver a la legislaci\u00f3n que impon\u00eda unas penas m\u00e1s graves\u201d, que seg\u00fan este partido es el mismo marco que acepta el PSOE.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-irene-montero-cree-que-el-pp-ha-humillado-al-psoe-con-la-ley-del-si-es-si\">Irene Montero cree que el PP \u201cha humillado\u201d al PSOE con la ley del s\u00ed es s\u00ed<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La ministra de Igualdad, Irene Montero, considera que el PP \u201cha humillado\u201d al PSOE al apoyar su propuesta de reforma de la ley del solo s\u00ed porque refuerza \u201ca\u00fan m\u00e1s\u201d volver al modelo penal de la violencia y ha lamentado que las alianzas que sirven para proteger el derecho a la vivienda no valgan para proteger los derechos de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Montero ha hecho estas declaraciones antes de visitar la exposici\u00f3n \u201c\u00bfQu\u00e9 llevabas puesto?\u201d y tras conocerse que el PP y el PSOE han alcanzado un acuerdo este lunes para corregir algunos aspectos de reforma de la ley del solo s\u00ed es s\u00ed durante la ponencia que estudia en el Congreso la proposici\u00f3n de ley impulsada por los socialistas y las enmiendas registradas por el resto de formaciones pol\u00edticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando al Partido Popular le das la mano, el Partido Popular te coge el brazo y lo que acaba de ocurrir es que el PP ha humillado al PSOE haci\u00e9ndole reforzar a\u00fan m\u00e1s esa vuelta al modelo penal anterior, el de la violencia o la intimidaci\u00f3n que basa la credibilidad de la v\u00edctima en funci\u00f3n de las heridas que la violencia del agresor ejerce sobre la v\u00edctima\u201d, ha reprochado la ministra. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El PP y el PSOE han alcanzado un acuerdo este lunes para corregir algunos aspectos de reforma de la ley del solo s\u00ed es s\u00ed, unas modificaciones que seg\u00fan los socialistas son \u201ct\u00e9cnicas\u201d, aunque para los populares \u201ctienen much\u00edsima importancia\u201d, seg\u00fan ha manifestado ambos grupos. Para los socios de investidura de Pedro S\u00e1nchez, son cambios [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-8070","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/8070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=8070"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/8070\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=8070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=8070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=8070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}