{"id":64313,"date":"2026-05-29T15:15:02","date_gmt":"2026-05-29T15:15:02","guid":{"rendered":"https:\/\/influencias.do\/?p=64313"},"modified":"2026-05-29T15:15:02","modified_gmt":"2026-05-29T15:15:02","slug":"ogtic-impulsa-la-modernizacion-de-los-servicios-academicos-de-la-uasd-mediante-firma-digital","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/05\/29\/ogtic-impulsa-la-modernizacion-de-los-servicios-academicos-de-la-uasd-mediante-firma-digital\/","title":{"rendered":"OGTIC impulsa la modernizaci\u00f3n de los servicios acad\u00e9micos de la UASD mediante firma digital"},"content":{"rendered":"<p>Santo Domingo. &#8211; La Oficina Gubernamental de Tecnolog\u00edas de la Informaci\u00f3n y Comunicaci\u00f3n (OGTIC) fortaleci\u00f3 el proceso de transformaci\u00f3n digital de la Universidad Aut\u00f3noma de Santo Domingo (UASD) mediante la implementaci\u00f3n de soluciones tecnol\u00f3gicas orientadas a modernizar los servicios acad\u00e9micos y optimizar la atenci\u00f3n a los estudiantes a trav\u00e9s de la plataforma FirmaGOB.<\/p>\n<p>Como parte de este proceso, fue inaugurado el Centro de Servicios Integrados de la UASD, que concentra las \u00e1reas de Registro, Admisiones y Archivo Central, incorporando 29 procesos digitales bajo el programa Burocracia Cero, establecido mediante el Decreto n\u00fam. 640-20.<\/p>\n<p>El acompa\u00f1amiento de la OGTIC se sustenta en pilares tecnol\u00f3gicos enfocados en garantizar agilidad, seguridad jur\u00eddica y eficiencia en los servicios acad\u00e9micos. Entre ellos, la digitalizaci\u00f3n de los procesos de emisi\u00f3n documental, permitiendo que certificaciones, r\u00e9cords de notas, cartas para exequ\u00e1tur y fotocopias de t\u00edtulos puedan gestionarse de manera m\u00e1s r\u00e1pida y segura.<\/p>\n<p>Otro componente clave es la implementaci\u00f3n de firma digital cualificada y sellos electr\u00f3nicos institucionales mediante FirmaGOB, asegurando autenticidad, integridad y validez jur\u00eddica en cada documento emitido por la universidad.<\/p>\n<p>Asimismo, el proyecto fortalece la interoperabilidad y la modernizaci\u00f3n de la atenci\u00f3n ciudadana mediante sistemas digitales de gesti\u00f3n de turnos, pantallas informativas y herramientas tecnol\u00f3gicas que optimizan la organizaci\u00f3n y capacidad de respuesta de los servicios universitarios.<\/p>\n<p>Con esta iniciativa, se estima la emisi\u00f3n anual de aproximadamente 800,000 documentos acad\u00e9micos firmados digitalmente, reduciendo tiempos de respuesta, costos operativos y procesos manuales.<\/p>\n<p>La participaci\u00f3n de la OGTIC reafirma su rol como instituci\u00f3n habilitadora de la transformaci\u00f3n digital del Estado dominicano, promoviendo modelos escalables de modernizaci\u00f3n y servicios digitales confiables para las instituciones p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. &#8211; La Oficina Gubernamental de Tecnolog\u00edas de la Informaci\u00f3n y Comunicaci\u00f3n (OGTIC) fortaleci\u00f3 el proceso de transformaci\u00f3n digital de la Universidad Aut\u00f3noma de Santo Domingo (UASD) mediante la implementaci\u00f3n de soluciones tecnol\u00f3gicas orientadas a modernizar los servicios acad\u00e9micos y optimizar la atenci\u00f3n a los estudiantes a trav\u00e9s de la plataforma FirmaGOB. Como parte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":1,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-64313","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=64313"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64313\/revisions"}],"predecessor-version":[{"id":64315,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64313\/revisions\/64315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/64314"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=64313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=64313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=64313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}