{"id":64143,"date":"2026-05-20T21:22:01","date_gmt":"2026-05-20T21:22:01","guid":{"rendered":"https:\/\/influencias.do\/?p=64143"},"modified":"2026-05-20T21:22:01","modified_gmt":"2026-05-20T21:22:01","slug":"gobierno-anuncia-licitacion-para-rescatar-el-teatro-agua-y-luz-buscan-convertir-el-espacio-en-escenario-cultural-y-turistico","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/05\/20\/gobierno-anuncia-licitacion-para-rescatar-el-teatro-agua-y-luz-buscan-convertir-el-espacio-en-escenario-cultural-y-turistico\/","title":{"rendered":"Gobierno anuncia licitaci\u00f3n para rescatar el Teatro Agua y Luz, buscan convertir el espacio en escenario cultural y tur\u00edstico"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Santo Domingo.<\/strong> El Gobierno iniciar\u00e1 el proceso de licitaci\u00f3n para la recuperaci\u00f3n del Teatro Agua y Luz, ubicado en el Centro de los H\u00e9roes, en Santo Domingo.<\/p>\n<p style=\"text-align: justify;\">El anuncio fue realizado durante el almuerzo que sostuvo el mandatario con representantes de la clase art\u00edstica dominicana en el Sal\u00f3n Verde del Palacio Nacional.<\/p>\n<p style=\"text-align: justify;\">El ministro de Turismo, David Collado, expres\u00f3 que el mandatario le instruy\u00f3 a realizar esa licitaci\u00f3n, y que el proyecto incluir\u00e1 remodelaci\u00f3n y techado.<\/p>\n<p style=\"text-align: justify;\">David Collado explic\u00f3 que ya fue autorizada la realizaci\u00f3n de un proceso de licitaci\u00f3n para intervenir la estructura y convertirla en un moderno escenario cultural y tur\u00edstico.<\/p>\n<p style=\"text-align: justify;\">\u201cPor instrucciones del presidente se autoriz\u00f3 que se hiciera un proceso de licitaci\u00f3n. Ya iniciamos el dise\u00f1o y el proceso para recuperar el Teatro Agua y Luz, incluyendo un techado que permita realizar actividades aunque el clima no favorezca\u201d, afirm\u00f3 el ministro atendiendo una llamada de telef\u00f3nica del mandatario.<\/p>\n<p style=\"text-align: justify;\">Indic\u00f3 que el proceso de licitaci\u00f3n ya fue publicado o estar\u00eda siendo colocado oficialmente durante esta misma semana, estimando que en aproximadamente tres meses podr\u00eda completarse el proceso administrativo previo al inicio de la construcci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cLa idea es que, concluido el proceso, se firme el contrato y de inmediato comiencen los trabajos\u201d, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify;\">Durante el encuentro, el presidente Abinader record\u00f3 que antes de asumir la Presidencia visit\u00f3 un teatro en la ciudad de Nashville, Estados Unidos, donde artistas de m\u00fasica country se presentaban cada fin de semana, experiencia que despert\u00f3 en \u00e9l el deseo de crear un espacio similar en la Rep\u00fablica Dominicana.<\/p>\n<p style=\"text-align: justify;\">\u201cSiempre so\u00f1\u00e9 con que nuestro pa\u00eds tuviera un lugar as\u00ed, donde los artistas dominicanos puedan presentarse de manera permanente y donde la cultura tambi\u00e9n sea parte del atractivo tur\u00edstico\u201d, expres\u00f3 el mandatario.<\/p>\n<p style=\"text-align: justify;\">Un espacio para impulsar la cultura y el turismo<\/p>\n<p style=\"text-align: justify;\">Collado explic\u00f3 que la visi\u00f3n del presidente Abinader es transformar el Teatro Agua y Luz en un referente cultural y tur\u00edstico para la ciudad de Santo Domingo.<\/p>\n<p style=\"text-align: justify;\">\u201cEl sue\u00f1o del presidente es que ese espacio se convierta en algo similar al Hard Rock Caf\u00e9 de Medell\u00edn, un lugar activo para presentaciones art\u00edsticas y eventos culturales\u201d, sostuvo.<\/p>\n<p style=\"text-align: justify;\">El funcionario agreg\u00f3 que el proyecto ser\u00e1 desarrollado junto a entidades vinculadas al sector tur\u00edstico y cultural, con el prop\u00f3sito de dinamizar la oferta de entretenimiento de la capital y crear un escenario permanente para artistas dominicanos.<\/p>\n<p style=\"text-align: justify;\">\u201cEse espacio es ideal para que los artistas puedan realizar presentaciones, pero lamentablemente lleva a\u00f1os abandonado\u201d, expres\u00f3 el cantante Rafa Rosario durante el encuentro.<\/p>\n<p style=\"text-align: justify;\">El contrato fue adjudicado en el gobierno de 2016 a 2020 a la empresa Consultor\u00eda Astur, S.A.<\/p>\n<p style=\"text-align: justify;\">La actividad cont\u00f3 con la presencia del ministro de Cultura, Roberto \u00c1ngel Salcedo, el ministro de Justicia, Antoliano Peralta, y el director de la Oficina Nacional de Derecho de Autor (ONDA), Jose Rub\u00e9n Gonell Cosme.<\/p>\n<p style=\"text-align: justify;\">Entre los artistas, compositores, m\u00fasicos, productores y representantes del sector cultural presentes en el encuentro estuvieron Ram\u00f3n Orlando, C\u00e9sar G. Acosta Chevalier, Francisco Ulloa, Kinito M\u00e9ndez, Fefita La Grande, Pakol\u00e9, Sergio Vargas, Manuel Aramis Camilo, Omega, Rafa Rosario, Luis Mariano Lantigua Reynoso, Virgilio E. Fr\u00edas Almanzar, El Prodigio, Eddy Herrera, Krisspy y Nelson D\u2019La Olla.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s Jos\u00e9 Dionicio Fern\u00e1ndez, David Kada, Blanca Mar\u00eda D\u00edaz Mart\u00ednez, La India Canela, Raquel Arias Jim\u00e9nez de L\u00f3pez, Rene Soli, Martha Candela, Orlando Lora, Jos\u00e9 R. Gonell Cosme, Johnnie Alberto Mercedes Castillo, Sylvio Mora, Jandy Ventura, El Blachy, Juan Ram\u00f3n Mota Castillo, Valerio De Le\u00f3n Severino, Fausto Polanco del Orbe, Mar\u00eda Steffan Rodr\u00edguez, Luz Marcela De La Cruz Peralta, Pochy Familia, Luis Segura, Jos\u00e9 Luis Segura H, Pablo Euriel, Romo\u00f1 Lluveres, Hilda Pichardo, Robert Liliano Campos y Yuri Dom\u00ednguez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. El Gobierno iniciar\u00e1 el proceso de licitaci\u00f3n para la recuperaci\u00f3n del Teatro Agua y Luz, ubicado en el Centro de los H\u00e9roes, en Santo Domingo. El anuncio fue realizado durante el almuerzo que sostuvo el mandatario con representantes de la clase art\u00edstica dominicana en el Sal\u00f3n Verde del Palacio Nacional. El ministro de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64143","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=64143"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64143\/revisions"}],"predecessor-version":[{"id":64145,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64143\/revisions\/64145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/64144"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=64143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=64143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=64143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}