{"id":64127,"date":"2026-05-20T14:00:41","date_gmt":"2026-05-20T14:00:41","guid":{"rendered":"https:\/\/influencias.do\/?p=64127"},"modified":"2026-05-20T14:00:41","modified_gmt":"2026-05-20T14:00:41","slug":"policia-ocupa-maquinas-tragamonedas-y-equipos-de-juegos-de-azar-en-operativos-en-sde","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/05\/20\/policia-ocupa-maquinas-tragamonedas-y-equipos-de-juegos-de-azar-en-operativos-en-sde\/","title":{"rendered":"Polic\u00eda ocupa m\u00e1quinas tragamonedas y equipos de juegos de azar en operativos en SDE"},"content":{"rendered":"<p>Agentes de la Subdirecci\u00f3n Regional de Inteligencia (Dintel) realizaron varios operativos en colmados y centros comerciales de distintos sectores de Santo Domingo Este, donde ocuparon m\u00e1quinas tragamonedas y otros equipos utilizados presuntamente para juegos de azar ilegales.<\/p>\n<p>De acuerdo con el informe preliminar, durante las intervenciones fueron incautadas seis m\u00e1quinas tragamonedas, tres monitores para juegos de azar, dos televisores utilizados para juegos de caballos, una laptop y un arma blanca.<\/p>\n<p>Las autoridades informaron que los operativos fueron ejecutados como resultado de labores de inteligencia, con el objetivo de contrarrestar actividades il\u00edcitas, reforzar el orden p\u00fablico y garantizar la seguridad ciudadana en el municipio.<\/p>\n<p>Todo lo ocupado permanece bajo custodia policial para los fines legales correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes de la Subdirecci\u00f3n Regional de Inteligencia (Dintel) realizaron varios operativos en colmados y centros comerciales de distintos sectores de Santo Domingo Este, donde ocuparon m\u00e1quinas tragamonedas y otros equipos utilizados presuntamente para juegos de azar ilegales. De acuerdo con el informe preliminar, durante las intervenciones fueron incautadas seis m\u00e1quinas tragamonedas, tres monitores para juegos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-64127","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=64127"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64127\/revisions"}],"predecessor-version":[{"id":64129,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64127\/revisions\/64129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/64128"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=64127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=64127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=64127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}