{"id":64005,"date":"2026-05-12T18:17:41","date_gmt":"2026-05-12T18:17:41","guid":{"rendered":"https:\/\/influencias.do\/?p=64005"},"modified":"2026-05-12T18:17:41","modified_gmt":"2026-05-12T18:17:41","slug":"trump-afirma-que-cuba-esta-pidiendo-ayuda-y-va-a-responder-con-dialogo","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/05\/12\/trump-afirma-que-cuba-esta-pidiendo-ayuda-y-va-a-responder-con-dialogo\/","title":{"rendered":"Trump afirma que Cuba \u00abest\u00e1 pidiendo ayuda\u00bb y va a responder con di\u00e1logo"},"content":{"rendered":"<p style=\"text-align: justify;\">El presidente de EE.UU., Donald Trump, asegur\u00f3 este martes que Cuba &#8220;est\u00e1 pidiendo ayuda&#8221; y que \u00e9l est\u00e1 dispuesto a hablar.<\/p>\n<p style=\"text-align: justify;\">&#8220;Cuba est\u00e1 pidiendo ayuda, \u00a1y vamos a hablar! Mientras tanto, \u00a1me voy a China!&#8221;,\u00a0escribi\u00f3\u00a0el mandatario en su cuenta de TruthSocial, en v\u00edspera de su viaje al gigante asi\u00e1tico para reunirse con el presidente Xi Jinping.<\/p>\n<p style=\"text-align: justify;\">En su publicaci\u00f3n, Trump afirm\u00f3 que &#8220;ning\u00fan republicano&#8221; le hab\u00eda hablado antes de Cuba, naci\u00f3n a la que calific\u00f3 de\u00a0&#8220;pa\u00eds fallido&#8221;\u00a0que, seg\u00fan \u00e9l, &#8220;solo va en una direcci\u00f3n:\u00a0\u00a1hacia abajo!&#8221;.<\/p>\n<h3 style=\"text-align: justify;\">La presi\u00f3n<\/h3>\n<p style=\"text-align: justify;\">Las declaraciones del mandatario se producen en medio de la escalada de medidas y sanciones de Washington contra la isla.<\/p>\n<p style=\"text-align: justify;\">El viernes de la semana pasada, el secretario de Estado de EE.UU., Marco Rubio,\u00a0avis\u00f3\u00a0que\u00a0planean imponer nuevas sanciones\u00a0contra Cuba. Esto, despu\u00e9s de que el 1 de mayo, Trump\u00a0firmara\u00a0una\u00a0orden ejecutiva que impone\u00a0otras medidas\u00a0contra el Gobierno de la isla, ampliando las restricciones existentes bajo la Ley de Poderes Econ\u00f3micos de Emergencia Internacional.<\/p>\n<p style=\"text-align: justify;\">En aplicaci\u00f3n de esa Orden Ejecutiva, el Departamento del Tesoro estadounidense incluy\u00f3 al Grupo de Administraci\u00f3n Empresarial S.A. (Gaesa) y a la empresa minera Moa Nickel S.A.\u00a0(MNSA) en la Lista de Nacionales Especialmente Designados.<\/p>\n<p style=\"text-align: justify;\">Desde\u00a0La Habana,\u00a0denunciaron\u00a0el jueves pasado\u00a0el &#8220;car\u00e1cter criminal de estas medidas de agresi\u00f3n dirigidas a rendir por hambre y desesperaci\u00f3n a toda la poblaci\u00f3n cubana&#8221;.<\/p>\n<p style=\"text-align: justify;\">Ese d\u00eda,\u00a0el canciller cubano, Bruno Rodr\u00edguez Parrilla, afirm\u00f3 que &#8220;el gobierno de los Estados Unidos\u00a0confirma su intenci\u00f3n genocida\u00a0contra la naci\u00f3n cubana&#8221;. Seg\u00fan las autoridades, las nuevas sanciones podr\u00edan derivar en represalias contra empresas, bancos y entidades extranjeras que mantengan relaciones comerciales con Cuba.<\/p>\n<h3 style=\"text-align: justify;\">Amenaza de EE.UU. a Cuba<\/h3>\n<p>El 29 de enero, el presidente de EE.UU., Donald Trump,\u00a0firm\u00f3\u00a0una orden ejecutiva que declara una\u00a0&#8220;emergencia nacional&#8221;\u00a0ante la supuesta\u00a0&#8220;amenaza inusual y extraordinaria&#8221;\u00a0que, seg\u00fan Washington, representar\u00eda Cuba para la seguridad del pa\u00eds norteamericano y la regi\u00f3n.<\/p>\n<p>El texto acusa al Gobierno cubano de alinearse con &#8220;numerosos pa\u00edses hostiles&#8221;, de acoger a &#8220;grupos terroristas transnacionales&#8221; y de permitir el despliegue en la isla de &#8220;sofisticadas capacidades militares y de inteligencia&#8221; de Rusia y de China.<\/p>\n<p>Sobre esas bases, se anunci\u00f3\u00a0la\u00a0imposici\u00f3n\u00a0de aranceles\u00a0a los pa\u00edses que vendan petr\u00f3leo a la naci\u00f3n antillana, a lo que se suman amenazas de represalias contra aquellos que act\u00faen contra la orden ejecutiva de la Casa Blanca.<\/p>\n<p>El paso se da en medio de una escalada entre Washington y\u00a0La Habana, que, sistem\u00e1ticamente,\u00a0ha rechazado esas alegaciones\u00a0y ha advertido que defender\u00e1 su integridad territorial. El presidente de Cuba\u00a0respondi\u00f3\u00a0que &#8220;esta nueva medida\u00a0evidencia la naturaleza fascista, criminal y genocida\u00a0de una camarilla que ha secuestrado los intereses del pueblo estadounidense con fines puramente personales&#8221;.<\/p>\n<p>El pasado 7 de marzo, Trump\u00a0anunci\u00f3\u00a0que &#8220;un gran cambio pronto llegar\u00e1 a Cuba&#8221;, a\u00f1adiendo que est\u00e1 llegando &#8220;al final del camino&#8221;.<\/p>\n<p>EE.UU. mantiene el bloqueo econ\u00f3mico y comercial contra Cuba\u00a0desde hace m\u00e1s de seis d\u00e9cadas.\u00a0El embargo, que afecta gravemente a la econom\u00eda del pa\u00eds, fue\u00a0ahora reforzado con numerosas medidas coercitivas y unilaterales por parte de la Casa Blanca.<\/p>\n<p>RT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de EE.UU., Donald Trump, asegur\u00f3 este martes que Cuba &#8220;est\u00e1 pidiendo ayuda&#8221; y que \u00e9l est\u00e1 dispuesto a hablar. &#8220;Cuba est\u00e1 pidiendo ayuda, \u00a1y vamos a hablar! Mientras tanto, \u00a1me voy a China!&#8221;,\u00a0escribi\u00f3\u00a0el mandatario en su cuenta de TruthSocial, en v\u00edspera de su viaje al gigante asi\u00e1tico para reunirse con el presidente Xi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":{"0":"post-64005","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacionales"},"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=64005"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64005\/revisions"}],"predecessor-version":[{"id":64007,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/64005\/revisions\/64007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/64006"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=64005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=64005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=64005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}