{"id":63954,"date":"2026-05-10T21:17:57","date_gmt":"2026-05-10T21:17:57","guid":{"rendered":"https:\/\/influencias.do\/?p=63954"},"modified":"2026-05-10T21:17:57","modified_gmt":"2026-05-10T21:17:57","slug":"queda-trabajo-por-hacer-netanyahu-dice-que-la-guerra-contra-iran-no-ha-terminado","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/05\/10\/queda-trabajo-por-hacer-netanyahu-dice-que-la-guerra-contra-iran-no-ha-terminado\/","title":{"rendered":"&#8220;Queda trabajo por hacer&#8221;: Netanyahu dice que la guerra contra Ir\u00e1n no ha terminado"},"content":{"rendered":"<p style=\"text-align: justify;\">La guerra de EE.UU. e Israel contra Ir\u00e1n <strong>no ha llegado a su fin<\/strong>, <a href=\"https:\/\/www.youtube.com\/watch?v=m-Q-OQEev6c\" target=\"_blank\" rel=\"noopener noreferrer\">afirm\u00f3<\/a> el domingo el primer ministro israel\u00ed, Benjam\u00edn Netanyahu, en una entrevista a CBS News.<\/p>\n<p style=\"text-align: justify;\">&#8220;Creo que [la guerra] <strong>logr\u00f3 mucho<\/strong>, pero no ha terminado, porque en Ir\u00e1n todav\u00eda queda material nuclear, uranio enriquecido, que debe ser retirado. Todav\u00eda hay instalaciones de <a href=\"https:\/\/actualidad.rt.com\/actualidad\/603391-eeuu-iran-negociar-moratoria-enriquecimiento-uranio\" target=\"_blank\" rel=\"noopener noreferrer\">enriquecimiento<\/a> que deben ser desmanteladas. Todav\u00eda existen fuerzas &#8216;proxy&#8217; que Ir\u00e1n apoya. Hay <strong>misiles <a href=\"https:\/\/actualidad.rt.com\/actualidad\/601345-saber-potencial-balistico-iran\" target=\"_blank\" rel=\"noopener noreferrer\">bal\u00edsticos<\/a><\/strong> que a\u00fan quieren producir. Ahora, hemos degradado gran parte de eso&#8221;, declar\u00f3 Netanyahu.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" style=\"text-align: justify;\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 Card-default\">\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">Sin embargo, seg\u00fan el l\u00edder israel\u00ed, &#8220;todo eso sigue ah\u00ed y a\u00fan <strong>queda trabajo por hacer<\/strong>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Hablando de un posible m\u00e9todo para retirar el uranio altamente enriquecido del pa\u00eds persa, se\u00f1al\u00f3 que el presidente estadounidense, <strong>Donald <a href=\"https:\/\/actualidad.rt.com\/actualidad\/604222-trump-prometer-obtener-uranio-enriquecido\" target=\"_blank\" rel=\"noopener noreferrer\">Trump<\/a><\/strong>, tiene ganas de entrar en el territorio iran\u00ed.<\/p>\n<p style=\"text-align: justify;\">&#8220;No voy a hablar de medios militares, pero lo que me ha dicho el presidente Trump es: &#8216;<strong>Quiero entrar all\u00ed<\/strong>&#8216;. Y creo que eso puede hacerse f\u00edsicamente&#8221;, dijo.<\/p>\n<p style=\"text-align: justify;\">En este contexto, argument\u00f3 que &#8220;ese no es el problema&#8221;. &#8220;Si hay un acuerdo y entras all\u00ed y lo sacas, \u00bfpor qu\u00e9 no? Esa <strong>es la mejor manera<\/strong>&#8220;, observ\u00f3 el primer ministro.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, <strong>se neg\u00f3 a comentar<\/strong> la posibilidad de sacar el uranio por la fuerza si no hay acuerdo.<\/p>\n<p style=\"text-align: justify;\">Al ser preguntado sobre\u00a0cu\u00e1nto tiempo llevar\u00e1 alcanzar ese objetivo, respondi\u00f3: &#8220;No voy a dar un calendario&#8221;. &#8220;Pero dir\u00e9 que esa es <strong>una misi\u00f3n tremendamente importante<\/strong>&#8220;, resumi\u00f3 Netanyahu.<\/p>\n<h3 style=\"text-align: justify;\">&#8220;Podemos sorprender al enemigo&#8221;<\/h3>\n<p style=\"text-align: justify;\">La misma jornada, el portavoz del Ej\u00e9rcito de Ir\u00e1n, el general de brigada Akrami Nia, <a href=\"https:\/\/esrt.press\/actualidad\/604181-iran-advertir-guerra-nuevos-escenarios-eeuu\" target=\"_blank\" rel=\"noopener noreferrer\">advirti\u00f3<\/a> que, si EE.UU. e Israel vuelven a cometer un &#8220;error de c\u00e1lculo&#8221; y emprenden una agresi\u00f3n contra su pa\u00eds, &#8220;sin duda&#8221; se enfrentar\u00e1n a <strong>&#8220;otras opciones sorpresa&#8221;<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan declar\u00f3, esas opciones incluir\u00edan &#8220;equipos m\u00e1s avanzados y nuevos&#8221;, &#8220;m\u00e9todos modernos de guerra&#8221; y, lo que consider\u00f3 m\u00e1s importante, <strong>&#8220;nuevos escenarios de combate&#8221;<\/strong>.<\/p>\n<p style=\"text-align: justify;\">&#8220;Es decir, la guerra entrar\u00e1 en \u00e1mbitos que el enemigo <strong>no ha previsto<\/strong> ni ha contemplado en sus planes, y en ese terreno podemos sorprender al enemigo&#8221;, afirm\u00f3 el portavoz.<\/p>\n<ul>\n<li style=\"text-align: justify;\">Antes de los ataques de Israel y\u00a0EE.UU. en junio del a\u00f1o pasado, <a href=\"https:\/\/esrt.press\/actualidad\/604222-trump-prometer-obtener-uranio-enriquecido\" target=\"_blank\" rel=\"noopener noreferrer\">se estimaba<\/a> que Ir\u00e1n dispon\u00eda de m\u00e1s de 400 kilogramos de uranio enriquecido al 60 %, as\u00ed como de casi 200 kilogramos de material con un nivel de enriquecimiento de alrededor del 20 %, que puede llevarse a un nivel apto para armas con relativa facilidad.<\/li>\n<li>\n<p style=\"text-align: justify;\">Durante esta nueva escalada, Washington\u00a0<a href=\"https:\/\/esrt.space\/actualidad\/598098-casa-blanca-deja-puerta-abierta\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">no ha descartado<\/a>\u00a0una operaci\u00f3n terrestre en caso de que Teher\u00e1n no renuncie a sus reservas de uranio enriquecido.<\/p>\n<\/li>\n<\/ul>\n<p>Fuebte RT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guerra de EE.UU. e Israel contra Ir\u00e1n no ha llegado a su fin, afirm\u00f3 el domingo el primer ministro israel\u00ed, Benjam\u00edn Netanyahu, en una entrevista a CBS News. &#8220;Creo que [la guerra] logr\u00f3 mucho, pero no ha terminado, porque en Ir\u00e1n todav\u00eda queda material nuclear, uranio enriquecido, que debe ser retirado. Todav\u00eda hay instalaciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-63954","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/63954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=63954"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/63954\/revisions"}],"predecessor-version":[{"id":63956,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/63954\/revisions\/63956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/63955"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=63954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=63954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=63954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}