{"id":62294,"date":"2026-03-03T19:28:52","date_gmt":"2026-03-03T19:28:52","guid":{"rendered":"https:\/\/influencias.do\/?p=62294"},"modified":"2026-03-03T19:28:52","modified_gmt":"2026-03-03T19:28:52","slug":"intrant-verifica-sistema-y-descarta-suplantacion-de-identidad-ciudadana-no-habia-iniciado-proceso-formal","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/03\/03\/intrant-verifica-sistema-y-descarta-suplantacion-de-identidad-ciudadana-no-habia-iniciado-proceso-formal\/","title":{"rendered":"INTRANT verifica sistema y descarta suplantaci\u00f3n de identidad; ciudadana no hab\u00eda iniciado proceso formal"},"content":{"rendered":"<p>Santo Domingo. \u2013 El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT) inform\u00f3 que, tras la denuncia realizada por Yahayra Elizabeth F\u00e9lix Cede\u00f1o sobre una presunta suplantaci\u00f3n de identidad en una de sus sedes de licencias, se procedi\u00f3 de inmediato a realizar la verificaci\u00f3n correspondiente en el sistema institucional.<\/p>\n<p>La instituci\u00f3n precis\u00f3 que lo \u00fanico presentado por la ciudadana ha sido, en el d\u00eda de hoy, un recibo correspondiente al pago de multas de tr\u00e1nsito, documento que no guarda relaci\u00f3n con la denuncia de presunta suplantaci\u00f3n ni con la emisi\u00f3n de carnet de aprendizaje o licencia de conducir.<\/p>\n<p>Luego de la revisi\u00f3n, se confirm\u00f3 que con el n\u00famero de c\u00e9dula de identidad indicado no se ha emitido ni entregado licencia de conducir ni carnet de aprendizaje, por lo que no existe suplantaci\u00f3n. Asimismo, se constat\u00f3 que la se\u00f1ora Yahayra Elizabeth F\u00e9lix Cede\u00f1o no hab\u00eda iniciado ning\u00fan proceso formal previo en el sistema de licencias.<\/p>\n<p>Los registros internos evidencian que acudi\u00f3 a solicitar la emisi\u00f3n del carnet de aprendizaje y tom\u00f3 turnos tanto en la sede central como en la oficina de Blue Mall; sin embargo, no complet\u00f3 el proceso en ninguna de las dos oficinas.<\/p>\n<p>De igual manera, se verific\u00f3 que manten\u00eda multas activas en el sistema al momento de solicitar el servicio. Conforme a lo establecido en la Ley 63-17 de Movilidad, Transporte Terrestre, Tr\u00e1nsito y Seguridad Vial de la Rep\u00fablica Dominicana, ning\u00fan conductor sancionado con el pago de una multa puede renovar ni tramitar su licencia de conducir, ni realizar gestiones asociadas, hasta tanto regularice su situaci\u00f3n. En consecuencia, mientras existan sanciones pendientes, el sistema impide continuar con el proceso solicitado.<\/p>\n<p>La instituci\u00f3n reiter\u00f3 que no se registr\u00f3 ninguna irregularidad en el sistema y que los procesos de emisi\u00f3n de licencias y carnets de aprendizaje cuentan con estrictos mecanismos de validaci\u00f3n de identidad, conforme a los datos oficiales de la Junta Central Electoral, lo que garantiza la seguridad y transparencia del servicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. \u2013 El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT) inform\u00f3 que, tras la denuncia realizada por Yahayra Elizabeth F\u00e9lix Cede\u00f1o sobre una presunta suplantaci\u00f3n de identidad en una de sus sedes de licencias, se procedi\u00f3 de inmediato a realizar la verificaci\u00f3n correspondiente en el sistema institucional. La instituci\u00f3n precis\u00f3 que lo \u00fanico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":1,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-62294","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/62294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=62294"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/62294\/revisions"}],"predecessor-version":[{"id":62296,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/62294\/revisions\/62296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/62295"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=62294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=62294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=62294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}