{"id":61320,"date":"2026-02-02T16:05:56","date_gmt":"2026-02-02T16:05:56","guid":{"rendered":"https:\/\/influencias.do\/?p=61320"},"modified":"2026-02-02T16:05:56","modified_gmt":"2026-02-02T16:05:56","slug":"abinader-llega-a-dubai-para-participar-en-la-cumbre-mundial-de-gobiernos-junto-a-lideres-del-mundo","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/02\/02\/abinader-llega-a-dubai-para-participar-en-la-cumbre-mundial-de-gobiernos-junto-a-lideres-del-mundo\/","title":{"rendered":"Abinader llega a Dub\u00e1i para participar en la Cumbre Mundial de Gobiernos junto a l\u00edderes del mundo"},"content":{"rendered":"<p>El presidente de la Rep\u00fablica Dominicana, Luis Abinader, lleg\u00f3 a Dub\u00e1i, Emiratos \u00c1rabes Unidos (EUA), para participar en la Cumbre Mundial de Gobiernos 2026 (World Governments Summit \u2013 WGS), un foro que re\u00fane a cientos de gobernantes de distintos pa\u00edses del mundo, as\u00ed como a empresarios e inversionistas, y que se celebrar\u00e1 del 3 al 5 de febrero bajo el lema \u201cDando forma al futuro de los gobiernos\u201d.<\/p>\n<p>La participaci\u00f3n del presidente Abinader en este foro de alto nivel reafirma el compromiso de la Rep\u00fablica Dominicana con el di\u00e1logo multilateral, la modernizaci\u00f3n del Estado, la atracci\u00f3n de inversiones y la construcci\u00f3n de pol\u00edticas p\u00fablicas orientadas al desarrollo sostenible y al bienestar de la poblaci\u00f3n.<\/p>\n<p>A su llegada, el mandatario dominicano fue recibido por Su Excelencia Huda Al Hashimi, ministra del Gobierno de los EAU y de Gabinete para Asuntos Estrat\u00e9gicos y el embajador de la Rep\u00fablica Dominicana ante los Emiratos \u00c1rabes Unidos, Renso Antonio Herrera Franco.<\/p>\n<p>Acompa\u00f1an al presidente Abinader los ministros de Hacienda, Magin Diaz, de Administraci\u00f3n P\u00fablica, Sigmund Freund y de Vivienda y Edificaciones, V\u00edctor -Ito- Bison\u00f3; el viceministro de Planificaci\u00f3n e Inversi\u00f3n P\u00fablica, Luis Madera Sued; la directora ejecutiva del Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana), Biviana Riveiro; la directora del Despacho Presidencial, Noelia Shephard Noelia Shephard y el director del Gabinete Presidencial, Eilyn Beltr\u00e1n.<\/p>\n<p>Durante la cumbre, el presidente Abinader se unir\u00e1 a otros l\u00edderes mundiales para debatir temas relacionados con la prosperidad econ\u00f3mica y las oportunidades emergentes, adem\u00e1s de sostener encuentros bilaterales con presidentes suramericanos y representantes de la comunidad dominicana.<\/p>\n<p>La Cumbre Mundial de Gobiernos es un evento anual de alto nivel que re\u00fane a jefes de Estado y de Gobierno, funcionarios, expertos y representantes del sector privado, con el objetivo de debatir sobre el futuro, la innovaci\u00f3n tecnol\u00f3gica, las pol\u00edticas p\u00fablicas y la sostenibilidad. Desde su creaci\u00f3n en 2013, se ha consolidado como una plataforma clave para el intercambio de ideas entre l\u00edderes de opini\u00f3n y formuladores de pol\u00edticas.<\/p>\n<p>El evento busca forjar soluciones a los desaf\u00edos globales venideros, con \u00e9nfasis en futurismo, innovaci\u00f3n, tecnolog\u00eda, gobernanza y cooperaci\u00f3n internacional.<\/p>\n<p>La Organizaci\u00f3n de la Cumbre Mundial de Gobiernos, a trav\u00e9s de sus eventos, di\u00e1logos y otras iniciativas, se enfoca en aprovechar la innovaci\u00f3n y la tecnolog\u00eda para abordar los desaf\u00edos universales que enfrenta la humanidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Rep\u00fablica Dominicana, Luis Abinader, lleg\u00f3 a Dub\u00e1i, Emiratos \u00c1rabes Unidos (EUA), para participar en la Cumbre Mundial de Gobiernos 2026 (World Governments Summit \u2013 WGS), un foro que re\u00fane a cientos de gobernantes de distintos pa\u00edses del mundo, as\u00ed como a empresarios e inversionistas, y que se celebrar\u00e1 del 3 al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61320","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/61320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=61320"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/61320\/revisions"}],"predecessor-version":[{"id":61322,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/61320\/revisions\/61322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/61321"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=61320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=61320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=61320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}