{"id":61317,"date":"2026-02-02T15:50:03","date_gmt":"2026-02-02T15:50:03","guid":{"rendered":"https:\/\/influencias.do\/?p=61317"},"modified":"2026-02-02T15:50:03","modified_gmt":"2026-02-02T15:50:03","slug":"arrestan-al-hijo-de-la-princesa-mette-marit-de-noruega-antes-del-juicio-por-violacion","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2026\/02\/02\/arrestan-al-hijo-de-la-princesa-mette-marit-de-noruega-antes-del-juicio-por-violacion\/","title":{"rendered":"Arrestan al hijo de la princesa Mette-Marit de Noruega antes del juicio por violaci\u00f3n"},"content":{"rendered":"<div class=\"entry-content\">\n<p>Marius Borg H\u00f8iby, hijo de la princesa Mette-Marit de\u00a0<a href=\"https:\/\/efe.com\/noticias\/noruega\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-mrf-link=\"https:\/\/efe.com\/noticias\/noruega\/\">Noruega<\/a>, ha sido arrestado la v\u00edspera, antes de afrontar el martes un juicio por varios casos de violaci\u00f3n y agresiones debido a la supuesta comisi\u00f3n de nuevos delitos, inform\u00f3 este lunes la Polic\u00eda de Oslo.<\/p>\n<p>\u00abMarius Borg H\u00f8iby fue detenido por la polic\u00eda el domingo por la noche y ha sido imputado por agresi\u00f3n corporal, amenazas con un cuchillo y quebrantamiento de la prohibici\u00f3n de visitar a una persona\u00bb, consta en un comunicado.<\/p>\n<p>La Polic\u00eda noruega ha informado de que H\u00f8iby comparecer\u00e1 ante el juez este lunes y que pedir\u00e1 cuatro semanas de prisi\u00f3n preventiva para \u00e9l debido al peligro de que vuelva a cometer nuevos delitos.<\/p>\n<h2 id=\"h-acusado-de-38-delitos\" class=\"wp-block-heading\">Acusado de 38 delitos<\/h2>\n<p>H\u00f8iby, de 29 a\u00f1os y que no es miembro de la Casa Real, ha sido acusado con anterioridad de 38 delitos, entre ellos cuatro casos de violaciones a distintas parejas mientras dorm\u00edan, seis de conducta sexual vejatoria; y otros de agresiones, amenazas, drogas, da\u00f1os, alteraci\u00f3n del orden p\u00fablico y de tr\u00e1fico.<\/p>\n<p>\u00abSe trata de actos muy graves que pueden dejar huella y destruir vidas. La pena m\u00e1xima para los delitos mencionados en la acusaci\u00f3n es de c\u00e1rcel de hasta diez a\u00f1os\u00bb, dijo el pasado 18 de agosto el fiscal, Sturla Henriksb\u00f8, al presentar la acusaci\u00f3n.<\/p>\n<p>El joven, que ha admitido tener problemas con el alcohol y otras drogas adem\u00e1s de padecer problemas ps\u00edquicos, ha reconocido s\u00f3lo los delitos de violencia contra una mujer, amenazas a un hombre y haber transportado varios kilos de marihuana hace seis a\u00f1os.<\/p>\n<p>EFE<\/p>\n<\/div>\n<footer class=\"entry-meta\" aria-label=\"Meta de entradas\"><\/footer>\n","protected":false},"excerpt":{"rendered":"<p>Marius Borg H\u00f8iby, hijo de la princesa Mette-Marit de\u00a0Noruega, ha sido arrestado la v\u00edspera, antes de afrontar el martes un juicio por varios casos de violaci\u00f3n y agresiones debido a la supuesta comisi\u00f3n de nuevos delitos, inform\u00f3 este lunes la Polic\u00eda de Oslo. \u00abMarius Borg H\u00f8iby fue detenido por la polic\u00eda el domingo por la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-61317","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/61317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=61317"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/61317\/revisions"}],"predecessor-version":[{"id":61319,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/61317\/revisions\/61319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/61318"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=61317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=61317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=61317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}