{"id":59666,"date":"2025-12-09T12:46:26","date_gmt":"2025-12-09T12:46:26","guid":{"rendered":"https:\/\/influencias.do\/?p=59666"},"modified":"2025-12-09T12:46:26","modified_gmt":"2025-12-09T12:46:26","slug":"rd15-mil-millones-desaparecidos-mp-exige-18-meses-de-coercion-para-implicados-en-caso-senasa","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/12\/09\/rd15-mil-millones-desaparecidos-mp-exige-18-meses-de-coercion-para-implicados-en-caso-senasa\/","title":{"rendered":"RD$15 mil millones desaparecidos: MP exige 18 meses de coerci\u00f3n para implicados en caso SeNaSa"},"content":{"rendered":"<p>SANTO DOMINGO. &#8211; Siguiendo con su lucha contra la corrupci\u00f3n administrativa, el Ministerio P\u00fablico solicit\u00f3 este lunes a un tribunal la imposici\u00f3n de 18 meses de prisi\u00f3n preventiva contra diez personas arrestadas en el marco de la Operaci\u00f3n Cobra por desfalcar al Estado dominicano con miles de millones de pesos del Seguro Nacional de Salud (SeNaSa).<\/p>\n<p>Santiago Marcelo F. Hazim Albainy, exdirector del SeNaSa, encabeza el grupo de imputados que integran, adem\u00e1s, Rafael Luis Mart\u00ednez Hazim, Gustavo Enrique Messina Cruz, Germ\u00e1n Rafael Robles Qui\u00f1ones, Francisco Iv\u00e1n Minaya P\u00e9rez, Eduardo Read Estrella, Cinty Acosta Senci\u00f3n, Ram\u00f3n Alan Speakler Mateo, Ada Ledesma Ubiera y Heidi Mariela Pineda Perdomo.<\/p>\n<p>Los fiscales Rosa Garc\u00eda, Enmanuel Ram\u00edrez, H\u00e9ctor Garc\u00eda, Yudelka Holgu\u00edn, Aurelio Valdez, Alexis Pi\u00f1a y Ernesto Guzm\u00e1n depositaron el documento en el que solicitaron a la Oficina Judicial de Servicios de Atenci\u00f3n Permanente del Distrito Nacional la imposici\u00f3n de prisi\u00f3n preventiva y la declaratoria del caso como de tramitaci\u00f3n compleja.<\/p>\n<p>H\u00e9ctor Garc\u00eda adelant\u00f3 que los imputados afectaron al SeNaSa con al menos 15 mil millones de pesos.<\/p>\n<p>La Direcci\u00f3n General de Persecuci\u00f3n del Ministerio P\u00fablico y la Procuradur\u00eda Especializada de Persecuci\u00f3n a la Corrupci\u00f3n Administrativa (Pepca), que encabezan el procurador adjunto Wilson Camacho, y la procuradora de corte Mirna Ortiz, est\u00e1n a cargo de las investigaciones que siguen en proceso.<\/p>\n<p>Entre otros delitos, al grupo se le imputan cargos de coalici\u00f3n de funcionarios, prevaricaci\u00f3n, asociaci\u00f3n de malhechores, cobro de soborno, estafa contra el Estado dominicano, desfalco, falsificaci\u00f3n, uso de documentos falsos y lavado de activos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. &#8211; Siguiendo con su lucha contra la corrupci\u00f3n administrativa, el Ministerio P\u00fablico solicit\u00f3 este lunes a un tribunal la imposici\u00f3n de 18 meses de prisi\u00f3n preventiva contra diez personas arrestadas en el marco de la Operaci\u00f3n Cobra por desfalcar al Estado dominicano con miles de millones de pesos del Seguro Nacional de Salud [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[108,1],"tags":[],"class_list":["post-59666","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mas-vistas","category-portada"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/59666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=59666"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/59666\/revisions"}],"predecessor-version":[{"id":59668,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/59666\/revisions\/59668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/59667"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=59666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=59666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=59666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}