{"id":589,"date":"2022-10-31T14:51:55","date_gmt":"2022-10-31T18:51:55","guid":{"rendered":"https:\/\/influencias.do\/2022\/10\/31\/el-excampeon-mundial-ajedrez-anatoli-karpov-en-coma-inducido\/"},"modified":"2022-10-31T14:51:55","modified_gmt":"2022-10-31T18:51:55","slug":"el-excampeon-mundial-ajedrez-anatoli-karpov-en-coma-inducido","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2022\/10\/31\/el-excampeon-mundial-ajedrez-anatoli-karpov-en-coma-inducido\/","title":{"rendered":"El excampe\u00f3n mundial ajedrez Anatoli K\u00e1rpov, en coma inducido"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"588\" src=\"https:\/\/influencias.do\/wp-content\/uploads\/2022\/10\/img_5102.jpg\" alt=\"\" class=\"wp-image-588\"\/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El excampe\u00f3n mundial de ajedrez Anatoli K\u00e1rpov, de 71 a\u00f1os, sufri\u00f3 una lesi\u00f3n craneoencef\u00e1lica a consecuencia de un accidente dom\u00e9stico, y se encuentra ahora en coma inducido en uno de los principales hospitales de la capital rusa, seg\u00fan declar\u00f3 hoy su hija Sof\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La hija del c\u00e9lebre ajedrecista neg\u00f3 en declaraciones al medio ruso Mash que este hubiera sido v\u00edctima de un ataque el pasado s\u00e1bado, seg\u00fan afirmaron varios canales de Telegram y publicaciones digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estos momentos, K\u00e1rpov se encuentra en estado de coma inducido en la unidad de cuidados intensivos del pabell\u00f3n de neurolog\u00eda del hospital Sklifosovski de Mosc\u00fa, uno de los centros m\u00e9dicos m\u00e1s prestigiosos de la capital rusa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anteriormente, el canal de Telegram ruso 112 inform\u00f3 de que el ajedrecista hab\u00eda sido hallado inconsciente junto a la sede de la Duma rusa el pasado s\u00e1bado, y que los m\u00e9dicos le hab\u00edan diagnosticado una lesi\u00f3n craneoencef\u00e1lica, una fractura de la cadera derecha y un fuerte estado de embriaguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">K\u00e1rpov, de 71 a\u00f1os, fue campe\u00f3n mundial entre 1975 y 1985, cuando fue vencido por el tambi\u00e9n ruso Garri Kasp\u00e1rov, y actualmente es diputado de la Duma, la camara baja del Parlamento ruso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La agencia rusa RIA N\u00f3vosti confirm\u00f3 con fuentes del hospital que el exajedrecista se encuentra ingresado en estado grave, sin embargo, cit\u00f3 el desmentido del jefe de relaciones p\u00fablicas de la Federaci\u00f3n Rusa de Ajedrez, Kiril Zangalis, que neg\u00f3 que se tratase de un ataque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La informaci\u00f3n de que Anatoli K\u00e1rpov fue golpeado no se corresponde a la realidad. Es una noticia falsa&#8221;, indic\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El excampe\u00f3n mundial de ajedrez Anatoli K\u00e1rpov, de 71 a\u00f1os, sufri\u00f3 una lesi\u00f3n craneoencef\u00e1lica a consecuencia de un accidente dom\u00e9stico, y se encuentra ahora en coma inducido en uno de los principales hospitales de la capital rusa, seg\u00fan declar\u00f3 hoy su hija Sof\u00eda. La hija del c\u00e9lebre ajedrecista neg\u00f3 en declaraciones al medio ruso Mash [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[123],"tags":[622,623,624,625],"class_list":["post-589","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","tag-ajedrez","tag-anatoli-karpov","tag-coma","tag-rusia"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=589"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/589\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}