{"id":57425,"date":"2025-10-10T14:28:12","date_gmt":"2025-10-10T14:28:12","guid":{"rendered":"https:\/\/influencias.do\/?p=57425"},"modified":"2025-10-10T14:28:12","modified_gmt":"2025-10-10T14:28:12","slug":"la-cadena-verde-transmitira-por-teleantillas-y-la-98-fm","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/10\/10\/la-cadena-verde-transmitira-por-teleantillas-y-la-98-fm\/","title":{"rendered":"La Cadena Verde transmitir\u00e1 por Teleantillas y La 98 FM"},"content":{"rendered":"<section class=\"nota-top-part\">\n<h1 class=\"font-700\" style=\"text-align: justify;\"><\/h1>\n<p class=\"font-700\" style=\"text-align: justify;\"><strong>SAN PEDRO DE MACOR\u00cdS<\/strong><span style=\"font-size: 16px;\"><strong>\u00a0.<\/strong>&#8211; Las Estrellas transmitir\u00e1n por medio a La Cadena Verde sus partidos como equipo due\u00f1o de casa, desde el Estadio Tetelo Vargas, en el torneo de b\u00e9isbol profesional que comenzar\u00e1 el 15 de octubre, con una cobertura nacional de radio y televisi\u00f3n.<\/span><\/p>\n<\/section>\n<div class=\"article-body\">\n<p style=\"text-align: justify;\">Por televisi\u00f3n, La Cadena Verde transmitir\u00e1 por Teleantillas (canal 10 de televisi\u00f3n), Coral 39, Estrellas HD en Claro 1096, Xtremo Channnel (canal 22).<\/p>\n<p style=\"text-align: justify;\">Por radio, los partidos desde el estadio de San Pedro de Macor\u00eds se escuchar\u00e1n por medio a\u00a0 una red de emisoras integrada por La 98 FM (emisora matriz) y Radio Dial (670 AM ), en San Pedro de Macor\u00eds y regi\u00f3n Este; as\u00ed como por La Voz de las Fuerzas Armadas (106.9 FM), con cobertura nacional.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n transmitir\u00e1n por medio al canal de You Tube @Estrellas Baseball Club.<\/p>\n<p style=\"text-align: justify;\">El personal que tendr\u00e1 a cargo esas transmisiones estar\u00e1 integrado por los narradores Ernesto Kranwinkel, Manuel Acevedo, \u00c1ngel Mota y Osvaldo Rodr\u00edguez Suncar. Tambi\u00e9n por los comentaristas Enrique \u2013Tuto- Mota, Fernando P\u00e9rez Ubiera y Luis Morales. El escucha de b\u00e9isbol y periodista Filiberto Fern\u00e1ndez estar\u00e1 como invitado.<\/p>\n<p style=\"text-align: justify;\">Los locutores comerciales de La Cadena Verde ser\u00e1n Raffy Ubiera, Luis Enrique y Siria Bello.<\/p>\n<p style=\"text-align: justify;\">LAS ANTESALAS<\/p>\n<p style=\"text-align: justify;\">Las Estrellas producir\u00e1n media hora antes de cada uno de sus partidos como equipo due\u00f1o de casa los programas Linterna Verde, por televisi\u00f3n: Tele Antillas, Coral 39, Estrellas HD en Claro 1096, Xtremo Channnel (canal 22); y por radio: La Antesala Verde (La 98 FM y Radio Dial).<\/p>\n<p style=\"text-align: justify;\">El programa Linterna Verde ser\u00e1 producido por los cronistas deportivos Manuel Acevedo, \u00c1ngel Mota y Osvaldo Rodr\u00edguez Suncar. La Antesala Verde ser\u00e1 una producci\u00f3n de los cronistas deportivos Luis Morales, Benjam\u00edn Mart\u00ednez y \u00c1ngel Luis Mercedes.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SAN PEDRO DE MACOR\u00cdS\u00a0.&#8211; Las Estrellas transmitir\u00e1n por medio a La Cadena Verde sus partidos como equipo due\u00f1o de casa, desde el Estadio Tetelo Vargas, en el torneo de b\u00e9isbol profesional que comenzar\u00e1 el 15 de octubre, con una cobertura nacional de radio y televisi\u00f3n. Por televisi\u00f3n, La Cadena Verde transmitir\u00e1 por Teleantillas (canal 10 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[123],"tags":[],"class_list":["post-57425","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/57425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=57425"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/57425\/revisions"}],"predecessor-version":[{"id":57431,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/57425\/revisions\/57431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/57427"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=57425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=57425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=57425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}