{"id":56006,"date":"2025-09-09T20:23:11","date_gmt":"2025-09-09T20:23:11","guid":{"rendered":"https:\/\/influencias.do\/?p=56006"},"modified":"2025-09-09T20:29:33","modified_gmt":"2025-09-09T20:29:33","slug":"exboxeador-joan-guzman-electo-a-la-inmortalidad-del-deporte-dominicano","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/09\/09\/exboxeador-joan-guzman-electo-a-la-inmortalidad-del-deporte-dominicano\/","title":{"rendered":"Exboxeador Joan Guzm\u00e1n electo a la inmortalidad del deporte dominicano"},"content":{"rendered":"<h1 class=\"nota-title mobile-article-title\" style=\"text-align: justify;\"><\/h1>\n<div class=\"nota-content\">\n<div class=\"nota-content-left\">\n<p style=\"text-align: justify;\">El Pabell\u00f3n de la Fama reservar\u00e1 una poltrona para Joan Guzm\u00e1n, pionero entre los atletas dominicanos con una medalla de oro en los Juegos Panamericanos, en un deporte individual.<\/p>\n<p style=\"text-align: justify;\">Guzm\u00e1n, cuya haza\u00f1a se remonta a los Panamericanos de Mar del Plata, Argentina, en 1995, es la sexta elecci\u00f3n que hace el Pabell\u00f3n de la Fama, de cara al ceremonial de la Clase Inmortal 2025 que efectuar\u00e1 el domingo 16 de noviembre en su auditorio del Centro Ol\u00edmpico Juan Pablo Duarte.<\/p>\n<p style=\"text-align: justify;\">El hito del tambi\u00e9n ex campe\u00f3n mundial de boxeo en la divisi\u00f3n supergallo y superpluma, era apenas el segundo t\u00edtulo logrado por la Rep\u00fablica Dominicana en una contienda continental, tras el oro conquistado por la selecci\u00f3n de b\u00e9isbol en la versi\u00f3n de M\u00e9xico \u201855.<\/p>\n<p style=\"text-align: justify;\">Nativo del populoso barrio de Guachupita, en Santo Domingo, el 1 de mayo de 1976, Guzm\u00e1n combin\u00f3 una carrera de estrella en el boxeo ol\u00edmpico y profesional, respectivamente.<\/p>\n<p style=\"text-align: justify;\">Su elegibilidad estuvo a cargo de los cronistas deportivos nacionales, responsables de escoger cada a\u00f1o a dos deportistas para la inmortalidad, a trav\u00e9s del voto electr\u00f3nico.<\/p>\n<p style=\"text-align: justify;\">Dionisio Guzm\u00e1n, presidente del Comit\u00e9 Permanente del Pabell\u00f3n de la Fama, dijo que adem\u00e1s de Joan, este a\u00f1o los comunicadores deportivos se decantaron por el ex pelotero de Grandes Ligas, Edwin Encarnaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Hasta el momento los otros deportistas elegidos para la inmortalidad son Jos\u00e9 Offerman, por el cap\u00edtulo de la Liga Dominicana de B\u00e9isbol; los ex grandes ligas Edwin Encarnaci\u00f3n y Jos\u00e9 Reyes, los propulsores Beato Miguel Cruz y Gonzalo Mej\u00eda, en voleibol y tenis de campo, sucesivamente. El empresario Manuel Estrella ser\u00e1 el Presidente de honor del Ceremonial.<\/p>\n<p style=\"text-align: justify;\">Guzm\u00e1n es uno de los boxeadores de m\u00e1s durabilidad como miembro de la selecci\u00f3n nacional de boxeo, al extremo de disputar m\u00e1s de 300 combates en el campo aficionado.<\/p>\n<p style=\"text-align: justify;\">En total, subi\u00f3 320 veces a los ensogados y sali\u00f3 victorioso en 310 de sus combates. Adem\u00e1s de su logro en Mar de Plata, Joan fue un asiduo representante dominicano en Juegos Centroamericanos y del Caribe y compiti\u00f3 en los Juegos Ol\u00edmpicos de 1996, en Atlanta.<\/p>\n<p style=\"text-align: justify;\">Inici\u00f3 su carrera en 1990 compitiendo en el Campeonato Nacional Infantil, ganando la medalla de oro y dos a\u00f1os m\u00e1s tarde ya se colgaba la diadema de monarca superior, conservando la corona en la versi\u00f3n nacional de Moca \u201993.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n en 1993, el p\u00fagil se proclam\u00f3 campe\u00f3n en la Copa Independencia de Boxeo, en el Festival Ol\u00edmpico de M\u00e9xico, Batalla de Carabobo (Venezuela), Copa Acapulco (M\u00e9xico) y la Copa Comelin (Colombia), combatiendo en los 48 kilogramos.<\/p>\n<p style=\"text-align: justify;\">Su primer evento grande fue en los Centroamericanos y del Caribe de Ponce \u201993, donde Guzm\u00e1n gan\u00f3 la medalla de oro derrotando en la final al local Jos\u00e9 Laureano.<\/p>\n<p style=\"text-align: justify;\">En este mismo a\u00f1o se coron\u00f3 en el Campeonato Centroamericano y del Caribe de La Habana, Cuba, donde fue elegido el boxeador m\u00e1s combativo del evento.<\/p>\n<p style=\"text-align: justify;\">En 1994 gan\u00f3 las preseas de oro en los torneos Batalla de Carabobo, Copa Romana, Copa Argentina, Copa Chile y Campeonato Centroamericano de Santi Spiritu, Cuba, ya como un pugilista de los 51 kilogramos.<\/p>\n<p style=\"text-align: justify;\">En 1995 se proclam\u00f3 campe\u00f3n en la Copa Sim\u00f3n Bol\u00edvar, Venezuela; Copa Independencia Nacional de Santiago; Copa Romana y el Centroamericano y del Caribe de Ciudad de M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">Repiti\u00f3 preseas de oro en la Copa Independencia Santiago \u201996, Copa Romana y en el Clasificatorio Ol\u00edmpico de Guaynabo (Puerto Rico), logrando su boleto a las Olimpiadas de Atlanta \u201996, evento en el que adem\u00e1s fue el abanderado de la Rep\u00fablica Dominicana.<\/p>\n<p style=\"text-align: justify;\">Tras la versi\u00f3n ol\u00edmpica de Atlanta, Joan dijo adi\u00f3s como miembro de la selecci\u00f3n, no sin antes marcharse con una envidiable cantidad de 21 medallas de oro ganadas en eventos internacionales, incluyendo los t\u00edtulos en los Centroamericanos Ponce \u201993 y los Panamericanos Mar del Plata \u201995, respectivamente.<\/p>\n<p style=\"text-align: justify;\"><strong>En profesional<\/strong><\/p>\n<p style=\"text-align: justify;\">Guzm\u00e1n dio el salto al boxeo de paga en 1997, debutando el 23 de septiembre contra Juan Miguel Rivera, a quien venci\u00f3 por nocaut t\u00e9cnico en Phoenix, Arizona.<\/p>\n<p style=\"text-align: justify;\">En 1999 se hizo con el t\u00edtulo de campe\u00f3n nacional del peso pluma derrotando por nocaut a Francisco de Le\u00f3n y en 2001 pulveriz\u00f3 en dos asaltos a H\u00e9ctor Julio \u00c1vila para ganar su primer t\u00edtulo internacional como profesional. Se hizo con el cetro regional supergallo de la NABO.<\/p>\n<p style=\"text-align: justify;\">En el mismo a\u00f1o defendi\u00f3 el t\u00edtulo intercontinental de la NABO ante Edel Ruiz, al tiempo que tambi\u00e9n ganaba la corona Latina de la Organizaci\u00f3n Mundial de Boxeo (OMB).<\/p>\n<p style=\"text-align: justify;\">Se coron\u00f3 campe\u00f3n mundial supergallo por primera vez el 12 de agosto del 2002, superando por nocaut a Fabio Oliva.<\/p>\n<p style=\"text-align: justify;\">Hizo su primera defensa, exitosa, contra su compatriota Agapito S\u00e1nchez, a quien noque\u00f3 en el s\u00e9ptimo asalto de la velada profesional celebrada el 26 de febrero de 2004 en San Diego, California.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n defendi\u00f3 la corona contra el invicto Fernando Beltr\u00e1n el 22 de abril del 2005, venciendo por decisi\u00f3n un\u00e1nime.<\/p>\n<p style=\"text-align: justify;\">Guzm\u00e1n gan\u00f3 el t\u00edtulo en otra categor\u00eda distinta, superando por decisi\u00f3n dividida a Jorge Rodr\u00edguez Barrio, en pelea por el peso s\u00faper pluma de la OMB celebrada el 16 de septiembre de 2006. En ese momento se convirti\u00f3 en el primer p\u00fagil dominicano campe\u00f3n en dos categor\u00edas diferentes.<\/p>\n<p style=\"text-align: justify;\">En el peso junior (126 libras), Guzm\u00e1n hizo dos defensas exitosas. El 18 de diciembre de 2018 en Santo Domingo, super\u00f3 por decisi\u00f3n dividida al norteamericano Antonio Davis; y el 17 de noviembre de 2007 frente al mexicano Humberto -Zorrita- Soto.<\/p>\n<p style=\"text-align: justify;\">Como profesional Joan Guzm\u00e1n realiz\u00f3 36 peleas, ganando 34 de ellas, 21 antes del l\u00edmite.<\/p>\n<p style=\"text-align: justify;\">Ahora con Joan Guzm\u00e1n, el Pabell\u00f3n de la Fama tendr\u00e1 23 boxeadores, siendo F\u00e9lix Amado G\u00f3mez (Kid Dinamita) y Octavio Almonte (Toro Isle\u00f1o) los exaltados en el primer ceremonial de 1967. Otros inmortales como pugilistas son Luis Emilio P\u00e9rez (Kid 22-22), 1969; Carlos -Teo- Cruz, 1970; Emilio S\u00e1nchez (Barquerito), 1973; Manuel de los Santos (Kid Langford), 1975; Vicente Cruz, 1976; Fausto Ceja Rodr\u00edguez, 1978; Julio -Juliot- L\u00f3pez, 1985; Natalio Jim\u00e9nez, 1986; Ignacio -Nacho- Espinal, 1989; y Carlos P\u00e9rez (El Zurdo del Higuamo), 1990.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n conservan un lugar en el Pabell\u00f3n de la Fama, Ventura Hern\u00e1ndez (Kid Ligerito), 1993; Leonardo -Leo- Cruz, 1994; Juan Guzm\u00e1n, 1995; Pedro Julio Nolasco, 1997; Eleoncio Mercedes, 1999; Lachi Linares, 2006: Miguel Montilla, 2015; Jorge -Salchich\u00f3n- Amparo, 2019;\u00a0 Manuel de Jes\u00fas Herrera (El Ol\u00edmpico), en 2020 y F\u00e9lix Manuel D\u00edaz, exaltado el a\u00f1o pasado.<\/p>\n<p style=\"text-align: justify;\"><strong>Fuente: Colimdo<\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Pabell\u00f3n de la Fama reservar\u00e1 una poltrona para Joan Guzm\u00e1n, pionero entre los atletas dominicanos con una medalla de oro en los Juegos Panamericanos, en un deporte individual. Guzm\u00e1n, cuya haza\u00f1a se remonta a los Panamericanos de Mar del Plata, Argentina, en 1995, es la sexta elecci\u00f3n que hace el Pabell\u00f3n de la Fama, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[123],"tags":[],"class_list":["post-56006","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/56006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=56006"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/56006\/revisions"}],"predecessor-version":[{"id":56008,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/56006\/revisions\/56008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/56007"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=56006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=56006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=56006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}