{"id":55989,"date":"2025-09-09T18:09:50","date_gmt":"2025-09-09T18:09:50","guid":{"rendered":"https:\/\/influencias.do\/?p=55989"},"modified":"2025-09-09T18:09:50","modified_gmt":"2025-09-09T18:09:50","slug":"gobierno-dominicano-realiza-primera-prueba-tecnica-del-sistema-nacional-de-alertas","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/09\/09\/gobierno-dominicano-realiza-primera-prueba-tecnica-del-sistema-nacional-de-alertas\/","title":{"rendered":"Gobierno dominicano realiza primera prueba t\u00e9cnica del Sistema Nacional de Alertas"},"content":{"rendered":"<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b>Santo Domingo.<\/b>\u00a0\u2013 En un esfuerzo interinstitucional, la vicepresidenta de la Rep\u00fablica Raquel Pe\u00f1a, junto al titular del Consejo Directivo del Instituto Dominicano de las Telecomunicaciones (INDOTEL), Guido G\u00f3mez Mazara, encabez\u00f3 la primera prueba t\u00e9cnica del Sistema Nacional de Alertas, una herramienta que permitir\u00e1 emitir mensajes de emergencia de manera masiva, inmediata y geolocalizada a los tel\u00e9fonos m\u00f3viles de la poblaci\u00f3n para salvaguardar vidas humanas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Este proyecto cuenta con el apoyo del Instituto Dominicano de las Telecomunicaciones (INDOTEL), el Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 9-1-1, Polic\u00eda Nacional, Ministerio P\u00fablico y el Centro de Operaciones de Emergencia (COE), junto a otras entidades, como la Oficina de Asuntos Internacionales de Narc\u00f3ticos y Aplicaci\u00f3n de la Ley del Departamento de Estado de los Estados Unidos (INL por sus siglas en ingl\u00e9s) y la embajada de los Estados Unidos, que unen esfuerzos para proteger la vida y la seguridad de la ciudadan\u00eda.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La primera prueba se realiz\u00f3 en la red de Claro Dominicana, por dispositivos Android, siendo esta la primera prestadora en adecuar sus sistemas a la tecnolog\u00eda Cell Broadcast (CB), que posibilita enviar notificaciones inmediatas y focalizadas \u00fanicamente en las zonas de riesgo. A diferencia de los tradicionales SMS, que resultaban lentos y poco precisos, esta nueva tecnolog\u00eda garantiza que las alertas lleguen en tiempo real y con pertinencia directa para quienes realmente las necesitan.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El sistema contempla dos grandes reg\u00edmenes de alerta: emergencia y desastres, gestionadas por el COE, abarcan fen\u00f3menos naturales como huracanes, inundaciones, terremotos o tsunamis. Esta instituci\u00f3n, que ya contaba con planes de contingencia para estos escenarios, ahora podr\u00e1 notificar con mayor agilidad a la poblaci\u00f3n y enfocar sus esfuerzos en las comunidades m\u00e1s afectadas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Tambi\u00e9n, las de seguridad ciudadana, coordinadas por Ministerio P\u00fablico, la Polic\u00eda Nacional y el 9-1-1, est\u00e1n orientadas a la b\u00fasqueda de personas desaparecidas. Aqu\u00ed se incluyen la Alerta Amber (ni\u00f1os), Alerta Rosa (mujeres en riesgo), Alerta Azul (personas con discapacidad) y Alerta Silver (adultos mayores). A diferencia de un simple anuncio, estas notificaciones buscan involucrar a la poblaci\u00f3n en la b\u00fasqueda, aportando informaci\u00f3n clave y v\u00edas de contacto con las autoridades.<\/div>\n<div><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-55990 aligncenter\" src=\"https:\/\/influencias.do\/wp-content\/uploads\/2025\/09\/G0aq3bSWwAAxUMd.jpg\" alt=\"\" width=\"554\" height=\"528\" srcset=\"https:\/\/influencias.do\/wp-content\/uploads\/2025\/09\/G0aq3bSWwAAxUMd.jpg 1200w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/09\/G0aq3bSWwAAxUMd-300x286.jpg 300w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/09\/G0aq3bSWwAAxUMd-1024x975.jpg 1024w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/09\/G0aq3bSWwAAxUMd-768x731.jpg 768w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/09\/G0aq3bSWwAAxUMd-860x818.jpg 860w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El presidente del Consejo Directivo de Indotel, Guido G\u00f3mez Mazara, resalt\u00f3 el valor vital de la inmediatez: \u201cLas estad\u00edsticas internacionales muestran que, en casos de desaparici\u00f3n de menores, el 80 % pierde la vida en las primeras 24 horas y un 94 % dentro de las 48 horas. La rapidez en la emisi\u00f3n de alertas es, literalmente, una herramienta para salvar vidas. Ese es el compromiso del Estado dominicano con este proyecto\u201d.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">De su lado, el director del Sistema 911 Rijo G\u00f3mez destac\u00f3: \u201cCon la puesta en marcha de la primera fase del Sistema Nacional de Alertas damos un paso firme hacia un futuro donde la tecnolog\u00eda, la coordinaci\u00f3n interinstitucional y la participaci\u00f3n activa de la ciudadan\u00eda se combinan para salvar vidas y fortalecer la seguridad p\u00fablica\u201d.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El sistema parte siempre de una denuncia, ya sea en un destacamento policial, el Ministerio P\u00fablico o una llamada al 9-1-1. Desde ese momento, se activa un protocolo que conecta a las autoridades: el 9-1-1 coordina la informaci\u00f3n, la Polic\u00eda Nacional despliega sus equipos en el terreno y la brinda acompa\u00f1amiento a las familias, realiza la coordinaci\u00f3n internacional y establece el r\u00e9gimen de consecuencias judiciales en caso de que medie la acci\u00f3n criminal.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Para garantizar su efectividad, el proyecto es respaldado por el convenio de colaboraci\u00f3n firmado entre Indotel y el Sistema 9-1-1, mediante el cual el \u00f3rgano regulador de las telecomunicaciones dispuso m\u00e1s de 900 mil d\u00f3lares para la compra, instalaci\u00f3n y puesta en funcionamiento de los equipos tecnol\u00f3gicos que hacen posible el Sistema de Nacional de Alertas. Estos fondos fueron aprobados por el Consejo Directivo de Indotel en su Sesi\u00f3n 027-2025, celebrada el 14 de agosto, consolidando la inversi\u00f3n estatal en infraestructura de seguridad.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Las autoridades precisaron que el sistema operar\u00e1 bajo protocolos estrictos, con redundancias tecnol\u00f3gicas en Santo Domingo y Santiago, lo que permitir\u00e1 garantizar la continuidad del servicio. Adem\u00e1s, cada alerta ser\u00e1 clara, breve y accionable, evitando la saturaci\u00f3n de mensajes y construyendo confianza en la poblaci\u00f3n.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Con esta primera prueba, Rep\u00fablica Dominicana da un paso firme hacia la implementaci\u00f3n progresiva del Sistema Nacional de Alertas, integrando la tecnolog\u00eda, coordinaci\u00f3n interinstitucional y la participaci\u00f3n activa de la ciudadan\u00eda, en beneficio de la seguridad p\u00fablica y la protecci\u00f3n de la vida humana.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En la actualidad se conoce en el Congreso Nacional el proyecto de ley de prevenci\u00f3n y respuesta nacional en caso de ausencia de poblaci\u00f3n vulnerable: \u201cAlerta Amber\u201d, que tiene como objeto regular el funcionamiento del Sistema Nacional de Alerta para la localizaci\u00f3n, asistencia y resguardo de las personas desaparecidas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A la primera prueba t\u00e9cnica asistieron Jos\u00e9 Ignacio Paliza, ministro de la Presidencia; Yeni Berenice Reynoso, procuradora general de la Rep\u00fablica; Feride Raful, ministra de Interior y Polic\u00eda; teniente general Carlos Antonio Fern\u00e1ndez Onofre y el ministro de Defensa.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Adem\u00e1s, Juan Manuel Mendez, director del Centro de Operaciones de Emergencias (COE); el director de la Polic\u00eda Nacional, mayor general Ram\u00f3n Antonio Guzm\u00e1n Peralta y el presidente del Senado de la Rep\u00fablica, Ricardo de los Santos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Por parte del Indotel estuvieron presentes los miembros Consejo Directivo Tom\u00e1s P\u00e9rez Ducy, Juan Taveras Hern\u00e1ndez, el viceministro de Econom\u00eda del Ministerio de Econom\u00eda y Hacienda, Alexis Cruz. Tambi\u00e9n se encontraban presentes la directora ejecutiva, Julissa Cruz; los directores de Despacho de Presidencia del Indotel, Alfredo L\u00f3pez Ariza; Gesti\u00f3n Humana, Juan Liranzo; Internacionales, Amparo Arango; Inform\u00e1tica, Jos\u00e9 Saba, entre otros calaboradores de esa instituci\u00f3n.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En representaci\u00f3n del sector de las telef\u00f3nicas acudieron al acto los presidentes de Claro Dominicana, Carlos Cueto; Wind Telecom, Jos\u00e9 Clase.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.\u00a0\u2013 En un esfuerzo interinstitucional, la vicepresidenta de la Rep\u00fablica Raquel Pe\u00f1a, junto al titular del Consejo Directivo del Instituto Dominicano de las Telecomunicaciones (INDOTEL), Guido G\u00f3mez Mazara, encabez\u00f3 la primera prueba t\u00e9cnica del Sistema Nacional de Alertas, una herramienta que permitir\u00e1 emitir mensajes de emergencia de manera masiva, inmediata y geolocalizada a los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55989","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/55989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=55989"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/55989\/revisions"}],"predecessor-version":[{"id":55992,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/55989\/revisions\/55992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/55991"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=55989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=55989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=55989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}