{"id":54418,"date":"2025-08-08T21:23:24","date_gmt":"2025-08-08T21:23:24","guid":{"rendered":"https:\/\/influencias.do\/?p=54418"},"modified":"2025-08-08T21:23:32","modified_gmt":"2025-08-08T21:23:32","slug":"este-pais-prohibira-el-acceso-de-personas-trans-a-lugares-publicos-exclusivos-para-mujeres","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/08\/08\/este-pais-prohibira-el-acceso-de-personas-trans-a-lugares-publicos-exclusivos-para-mujeres\/","title":{"rendered":"Este pa\u00eds prohibir\u00e1 el acceso de personas trans a lugares p\u00fablicos exclusivos para mujeres"},"content":{"rendered":"<div class=\"ArticleView-title\">\n<h1 class=\"HeadLine-root HeadLine-type_2 \" style=\"text-align: justify;\"><\/h1>\n<\/div>\n<div>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p style=\"text-align: justify;\">La Comisi\u00f3n de Igualdad y Derechos Humanos (EHRC, por sus siglas en ingl\u00e9s) del Reino Unido presentar\u00e1 ante la ministra de la Mujer e Igualdad, Bridget Phillipson, una gu\u00eda para limitar el acceso de personas trans* a espacios p\u00fablicos dirigidos exclusivamente a mujeres. Dichas directrices ser\u00e1n propuestas antes de que finalice este mes,\u00a0<a href=\"https:\/\/www.thetimes.com\/uk\/politics\/article\/trans-women-single-sex-spaces-ban-lr3hbgjzs\">recoge<\/a>\u00a0The Times.<\/p>\n<p style=\"text-align: justify;\">Se estima que Phillipson admitir\u00e1 dicho documento siempre y cuando se encuentre ajustado a la legislaci\u00f3n brit\u00e1nica. En este caso, la iniciativa proceder\u00e1 a debatirse en el Parlamento.<\/p>\n<p style=\"text-align: justify;\">La resoluci\u00f3n podr\u00eda prohibir el acceso de personas trans a ba\u00f1os y vestidores de diferentes establecimientos. Se detalla que no solo se trata de comercios como tiendas y gimnasios, sino tambi\u00e9n de escuelas, hospitales, prisiones y organismos gubernamentales.<\/p>\n<p style=\"text-align: justify;\">Con la nueva normativa, proveedores de servicios p\u00fablicos tendr\u00edan la libertad de pedir el documento de nacimiento a los ciudadanos para asegurar que estos espacios sean usados por personas de un solo g\u00e9nero biol\u00f3gico. Sin embargo, tienen que hacerlo de manera respetuosa y delicada. Si no, sus acciones pueden ser calificadas de discriminatorias.<\/p>\n<p style=\"text-align: justify;\">Asimismo, dentro de las directrices a contemplar existe la posibilidad de que se\u00a0proh\u00edba a las personas trans la participaci\u00f3n en competiciones deportivas femeninas.<\/p>\n<p style=\"text-align: justify;\">Mientras tanto, la comunidad transg\u00e9nero afirma que este cambio vulnerar\u00e1 sus derechos, por lo que prometen defenderse con acciones legales.<\/p>\n<p>Fuente RT<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Igualdad y Derechos Humanos (EHRC, por sus siglas en ingl\u00e9s) del Reino Unido presentar\u00e1 ante la ministra de la Mujer e Igualdad, Bridget Phillipson, una gu\u00eda para limitar el acceso de personas trans* a espacios p\u00fablicos dirigidos exclusivamente a mujeres. Dichas directrices ser\u00e1n propuestas antes de que finalice este mes,\u00a0recoge\u00a0The Times. Se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-54418","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/54418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=54418"}],"version-history":[{"count":2,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/54418\/revisions"}],"predecessor-version":[{"id":54421,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/54418\/revisions\/54421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/54419"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=54418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=54418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=54418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}