{"id":52907,"date":"2025-07-08T19:54:27","date_gmt":"2025-07-08T19:54:27","guid":{"rendered":"https:\/\/influencias.do\/?p=52907"},"modified":"2025-07-08T19:54:27","modified_gmt":"2025-07-08T19:54:27","slug":"medio-ambiente-somete-a-la-justicia-hotel-violaba-leyes-ambientales-en-punta-cana","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/07\/08\/medio-ambiente-somete-a-la-justicia-hotel-violaba-leyes-ambientales-en-punta-cana\/","title":{"rendered":"Medio Ambiente somete a la justicia hotel violaba leyes ambientales en Punta Cana"},"content":{"rendered":"<div><\/div>\n<div><\/div>\n<div>LA ALTAGRACIA (Republica Dominicana). \u2013 El Ministerio de Medio Ambiente y Recursos Naturales detuvo las labores en las playas de Uvero Alto, que realizaba el hotel Grand Sirenis Punta Cana, propiedad del Grupo Hotelero Matute, por violaciones a las normativas ambientales vigentes, relacionadas con el manejo adecuado del sargazo y el uso de equipos pesados en zonas costeras protegidas.<\/div>\n<div><\/div>\n<div>Las acciones ejecutadas por el hotel se llevaron a cabo sin permiso ambiental vigente para realizar intervenciones en el \u00e1rea costera, en contravenci\u00f3n a lo establecido en la Ley 64-00, sobre Medio Ambiente y Recursos Naturales.<\/div>\n<div>Ante dichas violaciones el Ministerio de Medio Ambiente ha iniciado el proceso de someter a la justicia a los infractores, para que sean sancionados conforme a la gravedad de los hechos.<\/div>\n<div><\/div>\n<div>El informe emitido por la Direcci\u00f3n de Fiscalizaci\u00f3n del Ministerio de Medio Ambiente, indica que, atendiendo a una denuncia recibida a trav\u00e9s de los canales disponibles en la instituci\u00f3n, se procedi\u00f3 a realizar una visita de verificaci\u00f3n.<\/div>\n<div><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-52883  aligncenter\" src=\"https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-1024x682.jpeg\" alt=\"\" width=\"710\" height=\"473\" srcset=\"https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-1024x682.jpeg 1024w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-300x200.jpeg 300w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-768x512.jpeg 768w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-1536x1023.jpeg 1536w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-330x220.jpeg 330w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-420x280.jpeg 420w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-615x410.jpeg 615w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM-860x573.jpeg 860w, https:\/\/influencias.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-1.54.38-PM.jpeg 1600w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/><\/div>\n<div><\/div>\n<div>Durante el operativo, realizado en coordinaci\u00f3n con el Servicio Nacional de Protecci\u00f3n Ambiental (SENPA), se pudo verificar la remoci\u00f3n total de la capa fre\u00e1tica del suelo en algunos puntos, lo cual representa una alteraci\u00f3n directa del equilibrio hidrogeol\u00f3gico costero.<\/div>\n<div><\/div>\n<div>Adem\u00e1s, se constat\u00f3 la ausencia de un gestor ambiental acreditado, a pesar de que los lineamientos obligan a que toda intervenci\u00f3n relacionada con el manejo de sargazo debe hacerse bajo la supervisi\u00f3n de un profesional ambiental calificado.<\/div>\n<div><\/div>\n<div>Asimismo, se comprob\u00f3 que se afect\u00f3 de manera directa zonas de anidamiento de tortugas marinas, espec\u00edficamente tortuga carey (<i>Eretmochelys imbricata<\/i>), especie en peligro cr\u00edtico de extinci\u00f3n y protegida por legislaci\u00f3n nacional e internacional.<\/div>\n<div><\/div>\n<div>Se encontr\u00f3 tambi\u00e9n acopio de sargazo dentro de la zona de pleamar, lo cual est\u00e1 prohibido seg\u00fan los lineamientos t\u00e9cnicos del Viceministerio de Recursos Costeros y Marinos, por representar un riesgo de contaminaci\u00f3n por descomposici\u00f3n, la cual afecta a la flora y fauna nativa.<\/div>\n<div><\/div>\n<div>Con esta acci\u00f3n el Ministerio de Medio Ambiente reafirma su compromiso con la protecci\u00f3n y preservaci\u00f3n de los recursos naturales en todo el territorio nacional.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>LA ALTAGRACIA (Republica Dominicana). \u2013 El Ministerio de Medio Ambiente y Recursos Naturales detuvo las labores en las playas de Uvero Alto, que realizaba el hotel Grand Sirenis Punta Cana, propiedad del Grupo Hotelero Matute, por violaciones a las normativas ambientales vigentes, relacionadas con el manejo adecuado del sargazo y el uso de equipos pesados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52907","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/52907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=52907"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/52907\/revisions"}],"predecessor-version":[{"id":52908,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/52907\/revisions\/52908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/52884"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=52907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=52907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=52907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}