{"id":52806,"date":"2025-07-07T01:50:25","date_gmt":"2025-07-07T01:50:25","guid":{"rendered":"https:\/\/influencias.do\/?p=52806"},"modified":"2025-07-07T01:50:25","modified_gmt":"2025-07-07T01:50:25","slug":"encienden-fuego-panamericano-inicia-relevo-antorcha-asu2026","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/07\/07\/encienden-fuego-panamericano-inicia-relevo-antorcha-asu2026\/","title":{"rendered":"Encienden fuego Panamericano; inicia relevo antorcha ASU2026"},"content":{"rendered":"<div class=\"nota-content\">\n<div class=\"redes-time\">\n<div class=\"n-time\" style=\"text-align: justify;\"><\/div>\n<\/div>\n<div class=\"nota-content-left\">\n<p style=\"text-align: justify;\">La llama Panamericana comienza desde hoy el recorrido por las principales ciudades de Paraguay, para culminar su periplo el pr\u00f3ximo 9 de agosto en la ceremonia inaugural de ASU 2025.<\/p>\n<p style=\"text-align: justify;\">La hermosa, hist\u00f3rica y tur\u00edstica Misi\u00f3n Jesu\u00edtica Jes\u00fas de Tavarangue en Paraguay, declarada Patrimonio de la Humanidad por la Unesco, fue el escenario perfecto para llevar a cabo la tan importante y tradicional ceremonia del encendido del fuego panamericano, en el marco de la antesala a lo que ser\u00e1n los II Juegos Panamericanos Junior ASU2025.<\/p>\n<p style=\"text-align: justify;\">Con las Ruinas Jesu\u00edticas\u00a0como escenograf\u00eda natural, se desarroll\u00f3 el evento que cont\u00f3 con la presencia de las m\u00e1ximas autoridades gubernamentales y deportivas del Paraguay y de Panam Sports.<\/p>\n<p style=\"text-align: justify;\">Tras el ingreso de las banderas y entonaci\u00f3n de himnos, llegaron las palabras de las autoridades presentes, quienes resaltaron la importancia de esta ceremonia y de la organizaci\u00f3n del evento deportivo m\u00e1s trascendental que sea realizado en Paraguay en sus 214 a\u00f1os de historia.<\/p>\n<p style=\"text-align: justify;\">\u201cEsta es una ceremonia muy tradicional en nuestra organizaci\u00f3n. En adultos, el encendido se hace siempre en Teotihuac\u00e1n M\u00e9xico. Para los primeros Juegos Panamericano Junior se realiz\u00f3 en el Cerro Cristo Rey en Cali y hoy nos encontramos en un lugar m\u00e1gico, lleno de historia y sumamente importante para la historia del Paraguay. Aqu\u00ed nace el fuego nuevo, para luego hacer un recorrido por diferentes rincones de este hermoso pa\u00eds hasta llegar el encendido del pebetero en la Ceremonia de Inauguraci\u00f3n. Estamos muy contentos, emocionados, ya no queda nada para que comience la fiesta deportiva para j\u00f3venes m\u00e1s importante del continente\u201d se\u00f1al\u00f3 el Presidente de Panam Sports Neven Ilic.<\/p>\n<p style=\"text-align: justify;\">\u201cDesde aqu\u00ed iniciar\u00e1 un recorrido, que no solo es un recorrido ceremonial. Es el reflejo de un proceso real palpable, de transformaci\u00f3n nacional. Porque ASU2025 no es un proyecto aislado, es parte de un proceso m\u00e1s amplio que incluye\u00a0inversi\u00f3n en infraestructura, impulso al turismo, generaci\u00f3n de empleo, formaci\u00f3n de talento y por supuesto, la proyecci\u00f3n internacional del Paraguay\u201d fueron las palabras de la m\u00e1xima autoridad del Paraguay, Santiago Pe\u00f1a.<\/p>\n<p style=\"text-align: justify;\">Tras los discursos entraron a escena ind\u00edgenas guaran\u00edes quienes al son de la m\u00fasica y sus bailes ancestrales, procedieron al encendido del fuego nuevo y de la antorcha panamericana, para comenzar as\u00ed del tradicional relevo.<\/p>\n<p style=\"text-align: justify;\">El primero en cargar con el Fuego Panamericano fue el presidente de Panam Sports Neven Ilic. Luego fue el turno del presidente de la Rep\u00fablica del Paraguay, Santiago Pe\u00f1a, sigui\u00f3 el Ministro de Deportes C\u00e9sar Ram\u00edrez, el presidente del COP, Camilo P\u00e9rez, un ind\u00edgena guaran\u00ed y, por \u00faltimo, seis atletas, que dieron por iniciado oficialmente el relevo de la antorcha panamericana.<\/p>\n<p style=\"text-align: justify;\">Durante 33 d\u00edas, la antorcha de los Juegos ASU 2025 estar\u00e1 recorriendo las principales ciudades del Paraguay hasta llegar el 9 de agosto al Estadio Defensores del Chaco en Asunci\u00f3n para la Ceremonia de Inauguraci\u00f3n.<\/p>\n<p>Fuente: Colimdo<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La llama Panamericana comienza desde hoy el recorrido por las principales ciudades de Paraguay, para culminar su periplo el pr\u00f3ximo 9 de agosto en la ceremonia inaugural de ASU 2025. La hermosa, hist\u00f3rica y tur\u00edstica Misi\u00f3n Jesu\u00edtica Jes\u00fas de Tavarangue en Paraguay, declarada Patrimonio de la Humanidad por la Unesco, fue el escenario perfecto para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[123],"tags":[],"class_list":["post-52806","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/52806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=52806"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/52806\/revisions"}],"predecessor-version":[{"id":52808,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/52806\/revisions\/52808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/52807"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=52806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=52806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=52806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}