{"id":51149,"date":"2025-06-06T21:26:41","date_gmt":"2025-06-06T21:26:41","guid":{"rendered":"https:\/\/influencias.do\/?p=51149"},"modified":"2025-06-06T21:26:47","modified_gmt":"2025-06-06T21:26:47","slug":"el-macabro-hallazgo-de-cuatro-cadaveres-esclarece-el-secuestro-de-una-comerciante-en-ecuador","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/06\/06\/el-macabro-hallazgo-de-cuatro-cadaveres-esclarece-el-secuestro-de-una-comerciante-en-ecuador\/","title":{"rendered":"El macabro hallazgo de cuatro cad\u00e1veres esclarece el secuestro de una comerciante en Ecuador"},"content":{"rendered":"<div class=\"ArticleView-title\">\n<h1 class=\"HeadLine-root HeadLine-type_2 \" style=\"text-align: justify;\"><\/h1>\n<\/div>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p style=\"text-align: justify;\">Al menos cuatro personas fueron encontradas sin vida en una cisterna de una vivienda del distrito de Nueva Prosperina, en el noroeste de la ciudad ecuatoriana de\u00a0<a href=\"https:\/\/actualidad.rt.com\/actualidad\/550688-nuevo-ataque-explosivos-barrio-guayaquil\" target=\"_blank\" rel=\"noopener noreferrer\">Guayaquil<\/a>, provincia de Guayas.<\/p>\n<p style=\"text-align: justify;\">Entre los cad\u00e1veres, seg\u00fan informaci\u00f3n preliminar, est\u00e1 el de una comerciante de nacionalidad china,\u00a0que\u00a0<strong>hab\u00eda sido secuestrada el pasado 29 de mayo\u00a0en su negocio<\/strong>, ubicado en la ciudadela Martha de Rold\u00f3s, inform\u00f3, en declaraciones a la prensa, el coronel V\u00edctor Ord\u00f3\u00f1ez Ron, comandante zonal de la Polic\u00eda en Guayaquil, Dur\u00e1n y Samborond\u00f3n.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\" style=\"text-align: justify;\">\n<div class=\"TwitterEmbed\">\n<div class=\"twitter-tweet twitter-tweet-rendered\"><iframe id=\"twitter-widget-0\" class=\"\" title=\"X Post\" src=\"https:\/\/platform.twitter.com\/embed\/Tweet.html?dnt=false&amp;embedId=twitter-widget-0&amp;features=eyJ0ZndfdGltZWxpbmVfbGlzdCI6eyJidWNrZXQiOltdLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X2ZvbGxvd2VyX2NvdW50X3N1bnNldCI6eyJidWNrZXQiOnRydWUsInZlcnNpb24iOm51bGx9LCJ0ZndfdHdlZXRfZWRpdF9iYWNrZW5kIjp7ImJ1Y2tldCI6Im9uIiwidmVyc2lvbiI6bnVsbH0sInRmd19yZWZzcmNfc2Vzc2lvbiI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfZm9zbnJfc29mdF9pbnRlcnZlbnRpb25zX2VuYWJsZWQiOnsiYnVja2V0Ijoib24iLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X21peGVkX21lZGlhXzE1ODk3Ijp7ImJ1Y2tldCI6InRyZWF0bWVudCIsInZlcnNpb24iOm51bGx9LCJ0ZndfZXhwZXJpbWVudHNfY29va2llX2V4cGlyYXRpb24iOnsiYnVja2V0IjoxMjA5NjAwLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X3Nob3dfYmlyZHdhdGNoX3Bpdm90c19lbmFibGVkIjp7ImJ1Y2tldCI6Im9uIiwidmVyc2lvbiI6bnVsbH0sInRmd19kdXBsaWNhdGVfc2NyaWJlc190b19zZXR0aW5ncyI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfdXNlX3Byb2ZpbGVfaW1hZ2Vfc2hhcGVfZW5hYmxlZCI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfdmlkZW9faGxzX2R5bmFtaWNfbWFuaWZlc3RzXzE1MDgyIjp7ImJ1Y2tldCI6InRydWVfYml0cmF0ZSIsInZlcnNpb24iOm51bGx9LCJ0ZndfbGVnYWN5X3RpbWVsaW5lX3N1bnNldCI6eyJidWNrZXQiOnRydWUsInZlcnNpb24iOm51bGx9LCJ0ZndfdHdlZXRfZWRpdF9mcm9udGVuZCI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9fQ%3D%3D&amp;frame=false&amp;hideCard=false&amp;hideThread=false&amp;id=1931029344094151060&amp;lang=es&amp;maxWidth=560px&amp;origin=https%3A%2F%2Factualidad.rt.com%2Factualidad%2F552707-hallan-cuatro-cuerpos-cisterna-ecuador&amp;sessionId=d6adb0f9008592b0bdcb409ad9d17d67d2d54abc&amp;siteScreenName=ActualidadRT&amp;theme=light&amp;widgetsVersion=2615f7e52b7e0%3A1702314776716&amp;width=550px\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"1931029344094151060\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">El uniformado indic\u00f3\u00a0que las tres v\u00edctimas restantes son hombres, uno de ellos ser\u00eda\u00a0<strong>otro comerciante y su ayudante<\/strong>; mientras que el tercero ser\u00eda\u00a0<strong>alguien que habr\u00eda sido secuestrado en Yaguachi<\/strong>, tambi\u00e9n en la provincia de Guayas.<\/p>\n<p style=\"text-align: justify;\">Detall\u00f3 que &#8220;los ciudadanos fueron encontrados sin vida,\u00a0<strong>asfixiados por sofocaci\u00f3n<\/strong>&#8220;; y adelant\u00f3 que hay tres detenidos por su presunta vinculaci\u00f3n con estos hechos.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" style=\"text-align: justify;\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 Card-default \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"><picture class=\"Picture-root Picture-default\"><source srcset=\" https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/thumbnail\/683f314159bf5b0ea93c9bf1.png 850w, https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/article\/683f314159bf5b0ea93c9bf1.png 1960w, \" media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" sizes=\"280px\" data-srcset=\" https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/thumbnail\/683f314159bf5b0ea93c9bf1.png 850w, https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/article\/683f314159bf5b0ea93c9bf1.png 1960w, \" \/><source srcset=\" https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/thumbnail\/683f314159bf5b0ea93c9bf1.png 460, https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/article\/683f314159bf5b0ea93c9bf1.png 980w, \" sizes=\"280px\" data-srcset=\" https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/thumbnail\/683f314159bf5b0ea93c9bf1.png 460, https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/article\/683f314159bf5b0ea93c9bf1.png 980w, \" \/><img decoding=\"async\" class=\"Picture-root Picture-default lazyautosizes lazyloaded\" src=\"https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/thumbnail\/683f314159bf5b0ea93c9bf1.png\" sizes=\"280px\" alt=\"Asamblea de Ecuador aprueba reforma para permitir la instalaci\u00f3n de bases militares extranjeras\" data-sizes=\"auto\" data-src=\"https:\/\/mf.b37mrtl.ru\/actualidad\/public_images\/2025.06\/thumbnail\/683f314159bf5b0ea93c9bf1.png\" \/><\/picture><\/div>\n<\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \"><a class=\"Link-root Link-isFullCard \" href=\"https:\/\/actualidad.rt.com\/actualidad\/552276-asamblea-ecuador-reforma-bases-militares-extranjeras\">Asamblea de Ecuador aprueba reforma para permitir la instalaci\u00f3n de bases militares extranjeras<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">De acuerdo con Ordo\u00f1ez, el lugar del hallazgo estaba alejado de la comunidad, en una colina de Nueva Prosperina, y este fue ubicado luego de que fuera detenido un presunto implicado en el secuestro de la comerciante, quien proporcion\u00f3 la informaci\u00f3n sobre la cisterna.<\/p>\n<p style=\"text-align: justify;\">Tras el descubrimiento, los cuerpos fueron trasladados a la morgue de Guayaquil, donde se realizar\u00e1n las autopsias correspondientes para\u00a0confirmar su identidad.<\/p>\n<p style=\"text-align: justify;\">Guayas, al igual que\u00a0Los R\u00edos,\u00a0Manab\u00ed, Orellana, Santa Elena, El Oro, Sucumb\u00edos, el\u00a0Distrito Metropolitano de Quito\u00a0en la provincia de Pichincha y el cant\u00f3n Camilo Ponce Enr\u00edquez de Azuay, se encuentra bajo\u00a0<strong>estado de excepci\u00f3n<\/strong>,\u00a0<a href=\"https:\/\/actualidad.rt.com\/actualidad\/546312-noboa-estado-excepcion-ecuador-elecciones\" target=\"_blank\" rel=\"noopener noreferrer\">decretado<\/a>\u00a0por el presidente del pa\u00eds, Daniel Noboa, en abril pasado, debido al &#8220;incremento de \u00edndices de\u00a0<a href=\"https:\/\/actualidad.rt.com\/video\/546026-noboa-fuerza-seguridad-pais\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">violencia<\/a>,\u00a0cometimiento de delitos\u00a0e intensidad de la perpetraci\u00f3n de il\u00edcitos por grupos armados organizados&#8221;.<\/p>\n<p style=\"text-align: justify;\">Fuente RT<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Al menos cuatro personas fueron encontradas sin vida en una cisterna de una vivienda del distrito de Nueva Prosperina, en el noroeste de la ciudad ecuatoriana de\u00a0Guayaquil, provincia de Guayas. Entre los cad\u00e1veres, seg\u00fan informaci\u00f3n preliminar, est\u00e1 el de una comerciante de nacionalidad china,\u00a0que\u00a0hab\u00eda sido secuestrada el pasado 29 de mayo\u00a0en su negocio, ubicado en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-51149","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/51149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=51149"}],"version-history":[{"count":2,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/51149\/revisions"}],"predecessor-version":[{"id":51152,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/51149\/revisions\/51152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/51150"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=51149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=51149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=51149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}