{"id":45786,"date":"2025-03-03T13:12:57","date_gmt":"2025-03-03T13:12:57","guid":{"rendered":"https:\/\/influencias.do\/?p=45786"},"modified":"2025-03-03T13:12:57","modified_gmt":"2025-03-03T13:12:57","slug":"intervienen-comercios-con-conexiones-irregulares-en-la-altagracia","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2025\/03\/03\/intervienen-comercios-con-conexiones-irregulares-en-la-altagracia\/","title":{"rendered":"Intervienen comercios con conexiones irregulares en La Altagracia"},"content":{"rendered":"<p>La Procuradur\u00eda General Adjunta para el Sistema El\u00e9ctrico (PGASE), en conjunto con la Empresa Distribuidora de Electricidad del Este (EDEESTE), ejecut\u00f3 un masivo operativo contra el fraude el\u00e9ctrico en la provincia de La Altagracia, revelando un esquema de conexiones irregulares que genera millonarias p\u00e9rdidas al sistema el\u00e9ctrico nacional.<\/p>\n<p>Durante la jornada, en la que participaron m\u00e1s de 15 fiscales de la PGASE, unos 15 agentes del orden y m\u00e1s de 20 equipos de esa procuradur\u00eda y de EDEESTE, se inspeccionaron varios comercios de alto consumo, se detectaron maniobras fraudulentas que afectaban la estabilidad y equidad del servicio el\u00e9ctrico.<\/p>\n<p>Entre los establecimientos notificados figuran Agrofem, Queso Don Eddy y un cuarto fr\u00edo operado por Carlos Manuel Medina de los Santos, donde se identificaron conexiones ilegales que permit\u00edan un consumo desproporcionado en relaci\u00f3n con la energ\u00eda facturada. EDEESTE determin\u00f3 que estos negocios consum\u00edan 33,327.4 kWh, equivalentes a RD$353,548.06 mensuales, mientras que su facturaci\u00f3n declarada era casi seis veces menor, reportando solo 4,620 kWh o RD$62,785.80 al mes.<\/p>\n<p>Este tipo de fraudes no solo representan un grave perjuicio econ\u00f3mico para la empresa distribuidora, sino que tambi\u00e9n afectan a los clientes que pagan su consumo de manera regular. La PGASE y EDEESTE reiteran su compromiso con la erradicaci\u00f3n de estas pr\u00e1cticas il\u00edcitas y continuar\u00e1n ejecutando operativos para garantizar un sistema el\u00e9ctrico m\u00e1s justo y sostenible.<\/p>\n<p>La provincia La Altagracia se ha convertido en un foco cr\u00edtico de fraude el\u00e9ctrico, registrando un alto \u00edndice de conexiones ilegales, especialmente en grandes comercios que consumen elevados vol\u00famenes de energ\u00eda sin pagar lo que realmente deben. Estas pr\u00e1cticas fraudulentas no solo generan p\u00e9rdidas millonarias para el sistema el\u00e9ctrico, sino que tambi\u00e9n afectan la calidad del servicio para los clientes regulares.<\/p>\n<p>Las autoridades advirtieron que realizar\u00e1n estos operativos en varios puntos del pa\u00eds y aplicar\u00e1n todo el peso de la ley a quienes incurran en estas irregularidades, reforzando las acciones para combatir el fraude el\u00e9ctrico y proteger los recursos de la naci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Procuradur\u00eda General Adjunta para el Sistema El\u00e9ctrico (PGASE), en conjunto con la Empresa Distribuidora de Electricidad del Este (EDEESTE), ejecut\u00f3 un masivo operativo contra el fraude el\u00e9ctrico en la provincia de La Altagracia, revelando un esquema de conexiones irregulares que genera millonarias p\u00e9rdidas al sistema el\u00e9ctrico nacional. Durante la jornada, en la que participaron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45787,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[2183,2005,4293,4294,4061],"class_list":["post-45786","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-comercios","tag-edeeste","tag-la-altragracia","tag-luz","tag-pgase"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/45786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=45786"}],"version-history":[{"count":1,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/45786\/revisions"}],"predecessor-version":[{"id":45788,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/45786\/revisions\/45788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media\/45787"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=45786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=45786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=45786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}