{"id":38760,"date":"2024-10-10T08:15:56","date_gmt":"2024-10-10T12:15:56","guid":{"rendered":"https:\/\/influencias.do\/?p=38760"},"modified":"2024-10-10T08:15:56","modified_gmt":"2024-10-10T12:15:56","slug":"rafa-nadal-anuncia-su-retirada-definitiva-del-tenis-profesional","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2024\/10\/10\/rafa-nadal-anuncia-su-retirada-definitiva-del-tenis-profesional\/","title":{"rendered":"Rafa Nadal anuncia su retirada definitiva del tenis profesional"},"content":{"rendered":"<p>El tenista espa\u00f1ol Rafael Nadal ha anunciado este jueves su retirada definitiva del tenis profesional, &#8220;tras unos a\u00f1os dif\u00edciles&#8221; en los que no ha sido capaz de &#8220;jugar sin limitaciones&#8221;, seg\u00fan ha contado en un video que ha hecho p\u00fablico a trav\u00e9s de sus redes sociales dando a conocer la noticia a todos sus seguidores.<\/p>\n<p>El tenista explic\u00f3\u00a0 que se trata de una decisi\u00f3n dif\u00edcil que ha necesitado tiempo para tomar.<\/p>\n<blockquote><p>&#8220;En esta vida todo tiene un principio y un final y creo que es el momento adecuado para poner punto y final a lo que ha sido una carrera larga y mucho m\u00e1s exitosa de lo que jam\u00e1s me habr\u00eda podido imaginar&#8221;, ha comentado.<\/p>\n<p>Nadal ha informado de que su \u00faltimo torneo ser\u00e1 la final de la Copa Davis, representando a su pa\u00eds, que se celebrar\u00e1 el pr\u00f3ximo mes de noviembre en la ciudad espa\u00f1ola de M\u00e1laga: &#8220;Creo que es cerrar el c\u00edrculo, porque una de mis primeras grandes alegr\u00edas como tenista profesional fue la final de Sevilla en 2004&#8221;, ha dicho.<\/p><\/blockquote>\n<p>El tenista ha tenido palabras de agradecimiento hacia toda la industria del tenis, para sus compa\u00f1eros, para su equipo y, tambi\u00e9n, para sus grandes rivales. Si bien no ha citado ning\u00fan nombre en concreto, sus palabras iban acompa\u00f1adas de im\u00e1genes del tenista suizo Roger Federer y el serbio Novak Djokovic.<\/p>\n<blockquote><p>&#8220;He pasado much\u00edsimas horas con ellos y he vivido muchos momentos que voy a recordar por el resto de mi vida&#8221;, les ha dedicado.<\/p><\/blockquote>\n<p>Tambi\u00e9n ha tenido una palabras muy emotivas dedicadas a su familia, entre los que ha nombrado a su madre, a su mujer, a su hijo, a su hermana, a su t\u00edo, &#8220;la raz\u00f3n&#8221; por la que empez\u00f3 a jugar al tenis, y a su padre.<\/p>\n<blockquote><p>&#8220;Me voy con la tranquilidad absoluta de haber dado el m\u00e1ximo, de haberme esforzado en todos los sentidos. Solo puedo terminar diciendo mil gracias a todos y hasta pronto&#8221;, concluye su mensaje.<\/p><\/blockquote>\n<p>Rafael Nadal es reconocido como uno de los grandes tenistas de todos los tiempos y el mejor en tierra batida. En su haber constan 22 t\u00edtulos de Grand Slam: 14 Roland Garros, 4 Abiertos de EE.UU., 2 Abiertos de Australia y 2 Wimbledon.<\/p>\n<p>Adem\u00e1s gan\u00f3 36 t\u00edtulos de Master 1000 y fue el tenista m\u00e1s joven en conseguir los 4 Gran Slam y la medalla de oro en los Juegos Ol\u00edmpicos. Ocup\u00f3 el n\u00famero 1 en el ranking de la ATP durante 209 semanas, siendo el \u00fanico en lograrlo en tres d\u00e9cadas diferentes.<\/p>\n<p>El ATP Tour ha sido la primera organizaci\u00f3n en reaccionar a la despedida de Nadal, con un tuit en el que acompa\u00f1a una composici\u00f3n con im\u00e1genes del tenista espa\u00f1ol con las palabras &#8220;Gracias, Rafa&#8221;. RT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tenista espa\u00f1ol Rafael Nadal ha anunciado este jueves su retirada definitiva del tenis profesional, &#8220;tras unos a\u00f1os dif\u00edciles&#8221; en los que no ha sido capaz de &#8220;jugar sin limitaciones&#8221;, seg\u00fan ha contado en un video que ha hecho p\u00fablico a trav\u00e9s de sus redes sociales dando a conocer la noticia a todos sus seguidores. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[123],"tags":[3776,1383,795],"class_list":["post-38760","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","tag-rafa-nadal","tag-retiro","tag-tenis"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/38760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=38760"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/38760\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=38760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=38760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=38760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}