{"id":31109,"date":"2024-04-20T19:14:59","date_gmt":"2024-04-20T23:14:59","guid":{"rendered":"https:\/\/influencias.do\/?p=31109"},"modified":"2024-04-20T19:14:59","modified_gmt":"2024-04-20T23:14:59","slug":"migrana-en-el-trabajo-como-debe-actuar-el-entorno-laboral","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2024\/04\/20\/migrana-en-el-trabajo-como-debe-actuar-el-entorno-laboral\/","title":{"rendered":"Migra\u00f1a en el trabajo: \u00bfC\u00f3mo debe actuar el entorno laboral?"},"content":{"rendered":"<p>Uno de cada siete trabajadores sufre migra\u00f1a, seg\u00fan datos que maneja la\u00a0<strong>Asociaci\u00f3n Espa\u00f1ola de Migra\u00f1a y Cefalea (AEMICE)<\/strong>, que ha lanzado la gu\u00eda\u00a0<strong>&#8220;La migra\u00f1a en el trabajo. Claves para promover un entorno laboral m\u00e1s inclusivo para personas con migra\u00f1a&#8221;<\/strong>, en la que han participado un comit\u00e9 editorial de expertos de diferentes disciplinas (neur\u00f3logos, enfermeras, m\u00e9dicos de familia, especialistas en recursos humanos y pacientes).<\/p>\n<p>La migra\u00f1a (un 15 % de prevalencia) y la\u00a0<a href=\"https:\/\/efesalud.com\/cefaleas-manual-primera-causa-demanda-asistencial-neurologica\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-wpel-link=\"internal\">cefalea<\/a>\u00a0tensional (m\u00e1s del 60 %) son los dos tipos de cefaleas m\u00e1s frecuentes entre m\u00e1s de doscientas, seg\u00fan datos de la\u00a0<strong>Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN)<\/strong>. Junto a las cefaleas en racimos son las dolencias que pueden ser cr\u00f3nicas.<\/p>\n<p>\u201cEsta cronicidad es especialmente habitual en el caso de la\u00a0<strong>migra\u00f1a<\/strong>, ya que m\u00e1s del 50 % de los pacientes espa\u00f1oles que padecen una cefalea cr\u00f3nica, padecen migra\u00f1a&#8221;, seg\u00fan el\u00a0<strong>doctor Pablo Irimia, coordinador del Grupo de Estudio de Cefaleas de la SEN.<\/strong><\/p>\n<p>Cefalea define cualquier tipo de dolor de cabeza que puede ser tanto un s\u00edntoma de otra enfermedad, algo que un 89 % de la poblaci\u00f3n masculina y un 99 % de la femenina asegura padecer o haber padecido en alg\u00fan momento de su vida, informa esta sociedad m\u00e9dica.<\/p>\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es la migra\u00f1a?<\/h2>\n<p>&#8220;Migra\u00f1a no es sufrir un simple dolor de cabeza&#8221;, se\u00f1ala la gu\u00eda de AEMICE. &#8220;Se manifiesta en forma de dolor de cabeza intenso y, en ocasiones, puls\u00e1til, como si se sintieran los latidos del coraz\u00f3n en la cabeza,<br \/>\nde intensidad moderada o severa que suele aparecer en un lado de la cabeza&#8221;.<\/p>\n<p>Tambi\u00e9n puede ir acompa\u00f1ada de alteraci\u00f3n de la sensibilidad a la luz, al sonido, a los olores, as\u00ed como n\u00e1useas y v\u00f3mitos.<\/p>\n<p>La migra\u00f1a se presenta en forma de ataques o crisis que pueden durar entre 4 y 72 horas. La frecuencia<br \/>\nde estas crisis es variable, pudiendo oscilar entre uno al a\u00f1o y varios por semana.<\/p>\n<h2 class=\"wp-block-heading\">Recomendaciones para abordar la migra\u00f1a en el trabajo<\/h2>\n<p>El 62 % de las personas con migra\u00f1a se sienten estigmatizadas en el trabajo y piden m\u00e1s apoyo a empresas y trabajadores, apunta AEMICE.<\/p>\n<p>Para facilitar la inclusi\u00f3n laboral de las personas con migra\u00f1a, esta asociaci\u00f3n recomienda a las empresas:<\/p>\n<ul>\n<li>Preguntar al trabajador o trabajadora\u00a0<strong>c\u00f3mo ayudarle<\/strong>.<\/li>\n<li>Facilitar al m\u00e1ximo\u00a0<strong>entornos<\/strong>\u00a0para prevenir y reducir la hipersensibilidad a la luz.<\/li>\n<li>Promover las\u00a0<strong>zonas de trabajo silenciosas<\/strong>.<\/li>\n<li>Crear\u00a0<strong>espacios ventilado<\/strong>s, libres de olores fuertes.<\/li>\n<li>Potenciar f\u00f3rmulas que permitan el\u00a0<strong>teletrabajo<\/strong>.<\/li>\n<li>Facilitar modelos de\u00a0<strong>flexibilidad horaria<\/strong>.<\/li>\n<li>Evitar<strong>\u00a0trabajos a turnos<\/strong>\u00a0u horario nocturno.<\/li>\n<li>Dar a conocer el\u00a0<strong>Servicio de Prevenci\u00f3n<\/strong>\u00a0de la empresa.<\/li>\n<li>Crear\u00a0<strong>programa<\/strong><em>s<\/em>\u00a0de educaci\u00f3n para la salud.<\/li>\n<li>Tener\u00a0<strong>informaci\u00f3n\u00a0<\/strong>sobre la migra\u00f1a y hacer pedagog\u00eda sobre su impacto.<\/li>\n<li>Valorar la posibilidad de cambiar al afectado de<strong>\u00a0puesto de trabajo<\/strong>.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo ayudar a mi compa\u00f1ero\/a durante una crisis de migra\u00f1a?<\/h2>\n<p>La gu\u00eda ofrece algunas pistas que pueden ser \u00fatiles para dar apoyo y facilitar un mejor entorno de trabajo:<\/p>\n<ul>\n<li>Transmitir que le crees.<\/li>\n<li>Evita los posibles desencadenantes de la migra\u00f1a como fragancias fuertes, velas perfumadas y productos de limpieza o exceso de ruido y m\u00fasica fuerte.<\/li>\n<li>Reconoce las cualidades de la persona al no ser f\u00e1cil vivir con esas limitaciones.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo controlo mi migra\u00f1a?<\/h2>\n<p>La\u00a0<a href=\"https:\/\/www.dolordecabeza.net\/wp-content\/uploads\/2024\/04\/guia-migrana-final-sueltas-abril2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\" data-wpel-link=\"external\">gu\u00eda de AEMICE<\/a>\u00a0tambi\u00e9n da consejos para que la migra\u00f1a afecte lo menos posible a la vida laboral:<\/p>\n<ul>\n<li>Controla el\u00a0<strong>estr\u00e9s.<\/strong><\/li>\n<li><strong>Programa<\/strong>\u00a0tus tareas.<\/li>\n<li>Adapta tu\u00a0<strong>espacio\u00a0<\/strong>de trabajo.<\/li>\n<li><strong>Bebe<\/strong>\u00a0con frecuencia y come sano y fuera de tu zona de trabajo.<\/li>\n<li><strong>Da a conocer tu enfermedad\u00a0<\/strong>en el entorno laboral.<\/li>\n<li><strong>Felic\u00edtate\u00a0<\/strong>por las peque\u00f1as victorias.<\/li>\n<li>Sigue las\u00a0<strong>pautas<\/strong>\u00a0de tu equipo sanitario.<\/li>\n<li>Contacta con\u00a0<strong>asociaciones\u00a0<\/strong>de pacientes.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Uno de cada siete trabajadores sufre migra\u00f1a, seg\u00fan datos que maneja la\u00a0Asociaci\u00f3n Espa\u00f1ola de Migra\u00f1a y Cefalea (AEMICE), que ha lanzado la gu\u00eda\u00a0&#8220;La migra\u00f1a en el trabajo. Claves para promover un entorno laboral m\u00e1s inclusivo para personas con migra\u00f1a&#8221;, en la que han participado un comit\u00e9 editorial de expertos de diferentes disciplinas (neur\u00f3logos, enfermeras, m\u00e9dicos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[2802],"tags":[],"class_list":["post-31109","post","type-post","status-publish","format-standard","has-post-thumbnail","category-salud"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/31109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=31109"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/31109\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=31109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=31109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=31109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}