{"id":31100,"date":"2024-04-20T17:46:12","date_gmt":"2024-04-20T21:46:12","guid":{"rendered":"https:\/\/influencias.do\/?p=31100"},"modified":"2024-04-20T17:46:12","modified_gmt":"2024-04-20T21:46:12","slug":"la-camara-baja-de-ee-uu-aprueba-una-ayuda-de-95-000-millones-para-ucrania-israel-y-taiwan","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2024\/04\/20\/la-camara-baja-de-ee-uu-aprueba-una-ayuda-de-95-000-millones-para-ucrania-israel-y-taiwan\/","title":{"rendered":"La C\u00e1mara baja de EE.UU. aprueba una ayuda de 95.000 millones para Ucrania, Israel y Taiw\u00e1n"},"content":{"rendered":"<p>La C\u00e1mara de Representantes de EE.UU. aprob\u00f3 un paquete de 95.000 millones de d\u00f3lares de ayuda exterior para Ucrania, Israel y Taiw\u00e1n, despu\u00e9s de que el proyecto de ley permaneci\u00f3 durante meses estancado por el bloqueo de un grupo de legisladores republicanos radicales.<\/p>\n<p>Cada partida se vot\u00f3 de manera independiente y los 61.000 millones para Ucrania se aprobaron por 311 votos bipartidistas a favor frente a 112 en contra, en una sesi\u00f3n en la que los dem\u00f3cratas vitorearon y ondearon banderas ucranianas.<\/p>\n<h2 id=\"h-fondos-para-israel-y-seguridad-del-indo-pacifico\" class=\"wp-block-heading\">Fondos para Israel y Seguridad del Indo-Pac\u00edfico<\/h2>\n<p>La partida de 26.400 millones para Israel fue aprobada por 366 votos a favor frente a 58 en contra e incluye fondos para los sistemas de defensa antimisiles as\u00ed como para la adquisici\u00f3n de sistemas de armas avanzados de defensa. 9.200 millones de d\u00f3lares son para asistencia humanitaria.<\/p>\n<p>En otra votaci\u00f3n, se aprobaron fondos para la seguridad del Indo-Pac\u00edfico (Taiw\u00e1n, entre otros) con un voto bipartidista de 385-34 m\u00e1s un voto en blanco, el de la representante dem\u00f3crata de EE.UU. de origen palestino Rashida Tlaib.<\/p>\n<p>Hay asignados 8.100 millones de d\u00f3lares para contrarrestar las acciones de China en la regi\u00f3n del Indo-Pac\u00edfico. Adem\u00e1s, se destinan 2.000 millones de d\u00f3lares en financiamiento militar extranjero para Taiw\u00e1n y otros aliados clave.<\/p>\n<h2 id=\"h-legislacion-de-seguridad-nacional-en-ee-uu\" class=\"wp-block-heading\">Legislaci\u00f3n de seguridad nacional en EE.UU.<\/h2>\n<p>El proyecto de ley tendr\u00e1 que ser ahora aprobado en el Senado, donde el Partido Dem\u00f3crata cuenta con una ajustada mayor\u00eda.<\/p>\n<p>Tras la aprobaci\u00f3n, el presidente de EE.UU. Joe Biden celebr\u00f3 en un comunicado que los legisladores hayan votado para promover \u201clos intereses de seguridad nacional\u201d del pa\u00eds. Tambi\u00e9n destac\u00f3 que se env\u00eda \u201cun mensaje claro sobre el poder del liderazgo estadounidense en el escenario mundial\u201d.<\/p>\n<p>\u201cEn este punto de inflexi\u00f3n cr\u00edtico, se unieron para responder al llamado de la historia, aprobando una legislaci\u00f3n de seguridad nacional que se necesitaba con urgencia y por la que he luchado durante meses\u201d, afirm\u00f3.<\/p>\n<h2 id=\"h-nuevo-rumbo-tras-ataque-a-israel\" class=\"wp-block-heading\">Nuevo rumbo tras ataque a Israel<\/h2>\n<p>El proyecto de ley hoy aprobado ha permanecido durante meses estancado en la C\u00e1mara Baja por el bloqueo de un grupo de legisladores que se opone a financiar a Ucrania, pero el reciente ataque de Ir\u00e1n a Israel le ha dado un nuevo impulso.<\/p>\n<p>Sin embargo, este s\u00e1bado se ha seguido el plan del presidente de la C\u00e1mara de Representantes, el republicano Mike Johnson, de dividir la aprobaci\u00f3n del proyecto en cuatro votaciones.<\/p>\n<h2 id=\"h-ee-uu-sanciones-y-potencial-veto-a-tiktok\" class=\"wp-block-heading\">EE.UU.: Sanciones y potencial veto a TikTok<\/h2>\n<p>En la cuarta votaci\u00f3n se han aglutinado varias demandas de los republicanos, entre ellas la imposici\u00f3n de sanciones a Ir\u00e1n, Rusia y China, y un potencial veto a TikTok.<\/p>\n<p>La C\u00e1mara de EE.UU. aprob\u00f3 la \u201cLey de Paz a trav\u00e9s de la Fuerza del Siglo XXI\u201d con un voto bipartidista de 360 a 58.<\/p>\n<p>Imponer sanciones a los puertos y refiner\u00edas que reciben y procesan petr\u00f3leo iran\u00ed; facultar al poder ejecutivo para confiscar y transferir activos rusos congelados en Estados Unidos a Ucrania; y darle a la matriz china de TikTok, ByteDance, nueve meses para vender la empresa de redes sociales son algunos de los conceptos que incluye.<\/p>\n<h2 id=\"h-financiamiento-para-ucrania-e-israel-en-el-foco\" class=\"wp-block-heading\">Financiamiento para Ucrania e Israel en el Foco<\/h2>\n<p>Tras la aprobaci\u00f3n de la C\u00e1mara de Representantes estas partidas deber\u00e1n pasar por el Senado, donde un proyecto muy similar ya fue aprobado el pasado febrero, y posteriormente el proyecto de ley ser\u00e1 promulgado por el presidente Joe Biden.<\/p>\n<p>El mandatario dem\u00f3crata lleva insistiendo desde octubre del a\u00f1o pasado para que el Congreso apruebe nuevo financiamiento para Ucrania e Israel.<\/p>\n<p>Durante meses, Mike Johnson se ha negado a someter a voto la ayuda exterior que pide Biden debido a que el ala m\u00e1s dura del Partido Republicano se opone a aprobar m\u00e1s ayuda militar para Ucrania, una posici\u00f3n que ha promovido el expresidente y precandidato republicano Donald Trump.<\/p>\n<p>El ataque de Ir\u00e1n a Israel presion\u00f3 a Johnson para aprobar la ayuda al pa\u00eds, principal aliado de EE. UU. en Oriente Medio y con respaldo republicano. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Representantes de EE.UU. aprob\u00f3 un paquete de 95.000 millones de d\u00f3lares de ayuda exterior para Ucrania, Israel y Taiw\u00e1n, despu\u00e9s de que el proyecto de ley permaneci\u00f3 durante meses estancado por el bloqueo de un grupo de legisladores republicanos radicales. Cada partida se vot\u00f3 de manera independiente y los 61.000 millones para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-31100","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/31100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=31100"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/31100\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=31100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=31100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=31100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}