{"id":27332,"date":"2024-02-02T18:23:02","date_gmt":"2024-02-02T22:23:02","guid":{"rendered":"https:\/\/influencias.do\/?p=27332"},"modified":"2024-02-02T18:23:02","modified_gmt":"2024-02-02T22:23:02","slug":"comision-de-camara-de-diputados-asistira-a-actividades-en-la-casa-blanca-y-en-el-capitolio","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2024\/02\/02\/comision-de-camara-de-diputados-asistira-a-actividades-en-la-casa-blanca-y-en-el-capitolio\/","title":{"rendered":"Comisi\u00f3n de C\u00e1mara de Diputados asistir\u00e1 a actividades en la Casa Blanca y en el Capitolio"},"content":{"rendered":"<p>SANTO DOMINGO.- Una delegaci\u00f3n de la <strong>C\u00e1mara de Diputados,<\/strong> encabezada por su presidente, Alfredo Pacheco, participar\u00e1 en la 6ta conferencia anual que organiza el congresista de los Estados Unidos, Adriano Espaillat, en la ciudad de Washington, en la que abordar\u00e1n la problem\u00e1tica social que afecta a los dominicanos en los Estados Unidos, como son: la migraci\u00f3n, seguridad, salud, ciberseguridad, as\u00ed como la inversi\u00f3n en el pa\u00eds de los dominicanos del exterior.<\/p>\n<p>Al explicar los alcances del evento, Pacheco inform\u00f3 que est\u00e1 pautado para iniciar el pr\u00f3ximo 6 de febrero con una actividad de gala organizada por la embajada dominicana en Washington.<\/p>\n<p>Para el d\u00eda 7 est\u00e1 previsto la celebraci\u00f3n de varios paneles donde van a exponer m\u00e1s de 50 l\u00edderes de origen dominicano, incluyendo al presidente Luis Abinader, que lo har\u00e1 de manera virtual.<\/p>\n<p>Tambi\u00e9n participar\u00e1 Chuck Schumer, l\u00edder de la mayor\u00eda del Senado de los Estados Unidos.<\/p>\n<p>Pacheco, al resaltar la importancia de este evento, manifest\u00f3 que existen 2 millones 800 mil dominicanos en el exterior que ejercen una influencia econ\u00f3mica en Rep\u00fablica Dominicana, los cuales env\u00edan cada a\u00f1o m\u00e1s de 10 mil millones de d\u00f3lares en remesas a sus familiares en el pa\u00eds.<\/p>\n<p>\u201cEsta actividad es extremadamente importante porque en ella se dan cita los principales exponentes de los diferentes estamentos de la pol\u00edtica Norteam\u00e9rica\u201d, afirm\u00f3.<\/p>\n<p>La delegaci\u00f3n dominicana estar\u00e1 encabezada por el presidente de los diputados, Alfredo Pacheco, as\u00ed como por Ignacio Aracena, presidente de la Comisi\u00f3n Permanente de Dominicanos en el Exterior y los legisladores, Ramon Ceballos, Kenia Bid\u00f3, Lily Florentino, Ramon Dorrejo, S\u00f3crates P\u00e9rez y\u00a0Heriberto Aracena.<\/p>\n<div class=\"gmail_signature\" dir=\"ltr\" data-smartmail=\"gmail_signature\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Una delegaci\u00f3n de la C\u00e1mara de Diputados, encabezada por su presidente, Alfredo Pacheco, participar\u00e1 en la 6ta conferencia anual que organiza el congresista de los Estados Unidos, Adriano Espaillat, en la ciudad de Washington, en la que abordar\u00e1n la problem\u00e1tica social que afecta a los dominicanos en los Estados Unidos, como son: la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-27332","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/27332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=27332"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/27332\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=27332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=27332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=27332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}