{"id":26155,"date":"2024-01-03T15:22:23","date_gmt":"2024-01-03T19:22:23","guid":{"rendered":"https:\/\/influencias.do\/?p=26155"},"modified":"2024-01-03T15:22:23","modified_gmt":"2024-01-03T19:22:23","slug":"salud-publica-dice-que-tiene-capacidad-de-medicamentos-e-insumos-para-tratar-casos-de-covid-19","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2024\/01\/03\/salud-publica-dice-que-tiene-capacidad-de-medicamentos-e-insumos-para-tratar-casos-de-covid-19\/","title":{"rendered":"Salud P\u00fablica dice que tiene capacidad de medicamentos e insumos para tratar casos de COVID-19"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">SANTO DOMINGO, R.D.- El Ministerio de Salud P\u00fablica inform\u00f3 este mi\u00e9rcoles que cuentan con capacidad de respuesta y disponibilidad de medicamentos e insumos para tratar los casos de COVID-19, que sean necesarios, pero advirti\u00f3 que no hay motivos de alarma, no obstante la poblaci\u00f3n debe continuar las medidas de higiene y un mayor cuidado a las personas con enfermedades inmunodeprimidas, ya que la enfermedad sigue circulando en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El doctor Eladio P\u00e9rez, viceministro de Salud Colectiva indic\u00f3 que cient\u00edficamente se ha comprobado que el medicamento Remdesivir es efectivo para la subvariante JN.1 Y asegur\u00f3 que en las pr\u00f3ximas horas dar\u00e1n a conocer los resultados para determinar si existen otros casos de Covid-19 que est\u00e9n asociados a esa variante, no obstante, recalc\u00f3 que desde la identificaci\u00f3n de los tres primeros, semanas atr\u00e1s, no hay reporte de m\u00e1s casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn cuanto a las hospitalizaciones no se ha identificado ning\u00fan estado cr\u00edtico y estamos viendo que ha aumentado la afluencia de pacientes a realizarse las pruebas. Respecto a las variantes todav\u00eda no est\u00e1n listas las pruebas, pero seguimos vigilantes para poder ver en qu\u00e9 proporci\u00f3n se sigue identificando la JN.1 y otras variantes.\u201d Dijo el doctor P\u00e9rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reitero a la poblaci\u00f3n a continuar las medidas de higiene y poner especial cuidado a las personas con enfermedades inmunodeprimidas, ya que estas son m\u00e1s vulnerables a cualquier tipo de virus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que las personas de mayor riesgo son aquellas que tienen enfermedades como VIH, c\u00e1ncer, asma, afecciones pulmonares, entre otras que comprometen las defensas del organismo y por ende este segmento de la poblaci\u00f3n requiere cuidados especiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las recomendaciones para la poblaci\u00f3n general son: evitar lugares con poca ventilaci\u00f3n, mantener el lavado de manos con agua y jab\u00f3n, si tienen gripe usar mascarillas para evitar esparcirla y el uso de estas sigue siendo recomendado en centro de salud. La alimentaci\u00f3n adecuada a base de frutas y vegetales y alimentos que contengan prote\u00ednas, adem\u00e1s la buena hidrataci\u00f3n, ayudan a fortalecer el sistema inmunitario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bolet\u00edn Covid-19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el bolet\u00edn 1,139, correspondiente a la Semana Epidemiol\u00f3gica 52, fueron identificados 252 nuevos casos, para un total de 260 activos, pero no ha habido casos severos durante esa semana se realiz\u00f3 un total de 2,434 pruebas, 87 PCR y 2,347 antig\u00e9nicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud llama a la poblaci\u00f3n a completar el esquema de vacunaci\u00f3n en los puestos fijos donde podr\u00e1n recibir vacunas contra la influenza y otros biol\u00f3gicos principalmente para ni\u00f1os, ni\u00f1as, adultos mayores de 65 a\u00f1os y embarazadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO, R.D.- El Ministerio de Salud P\u00fablica inform\u00f3 este mi\u00e9rcoles que cuentan con capacidad de respuesta y disponibilidad de medicamentos e insumos para tratar los casos de COVID-19, que sean necesarios, pero advirti\u00f3 que no hay motivos de alarma, no obstante la poblaci\u00f3n debe continuar las medidas de higiene y un mayor cuidado a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-26155","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/26155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=26155"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/26155\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=26155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=26155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=26155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}