{"id":25027,"date":"2023-12-12T11:05:34","date_gmt":"2023-12-12T15:05:34","guid":{"rendered":"https:\/\/influencias.do\/?p=25027"},"modified":"2023-12-12T11:05:34","modified_gmt":"2023-12-12T15:05:34","slug":"camara-de-representantes-de-ee-uu-planea-votar-sobre-juicio-politico-a-biden-este-miercoles","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/12\/12\/camara-de-representantes-de-ee-uu-planea-votar-sobre-juicio-politico-a-biden-este-miercoles\/","title":{"rendered":"C\u00e1mara de Representantes de EE.UU. planea votar sobre juicio pol\u00edtico a Biden este mi\u00e9rcoles"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los republicanos de la C\u00e1mara de Representantes de EE.UU. planean llevar a cabo este mi\u00e9rcoles una votaci\u00f3n para formalizar su investigaci\u00f3n de&nbsp;<strong>juicio pol\u00edtico<\/strong>&nbsp;contra el presidente del pa\u00eds, Joe Biden, reporta&nbsp;<a href=\"https:\/\/www.reuters.com\/world\/us\/us-house-vote-thursday-formalizing-biden-impeachment-inquiry-lawmaker-2023-12-11\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reuters<\/a>, citando a una fuente an\u00f3nima.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de la votaci\u00f3n en el pleno, la resoluci\u00f3n pertinente se presentar\u00e1 este martes ante el Comit\u00e9 de Reglas de la C\u00e1mara,\u00a0informa\u00a0<a href=\"https:\/\/www.nbcnews.com\/politics\/congress\/house-republicans-wednesday-vote-joe-biden-impeachment-inquiry-rcna129142\" target=\"_blank\" rel=\"noreferrer noopener\">NBC News<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La semana pasada,&nbsp;la republicana Kelly Armstrong&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/491620-republicanos-camara-eeuu-juicio-politico-biden\" target=\"_blank\" rel=\"noreferrer noopener\">present\u00f3<\/a>&nbsp;una&nbsp;resoluci\u00f3n que busca formalizar la investigaci\u00f3n para destituir a Joe Biden. El documento pide&nbsp;a los comit\u00e9s del Poder Judicial, de Supervisi\u00f3n y de Medios y Arbitrios que determinen &#8220;si existen motivos suficientes&#8221; para acusar al mandatario, a quien han venido investigando por&nbsp;<strong>beneficiarse de las actividades de negocio en el extranjero realizadas por su hijo Hunter<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pesquisa fue&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/479655-republicanos-juicio-politico-biden-eeuu\" target=\"_blank\" rel=\"noreferrer noopener\">iniciada<\/a>&nbsp;el pasado mes de septiembre por el entonces presidente de la C\u00e1mara, Kevin McCarthy. A su vez, el portavoz de Supervisi\u00f3n e Investigaciones de la Casa Blanca, Ian Sams,&nbsp;<a href=\"https:\/\/thehill.com\/homenews\/administration\/4347957-white-house-knocks-impeachment-inquiry-resolution\/\" target=\"_blank\" rel=\"noreferrer noopener\">calific\u00f3<\/a>&nbsp;el proceso de&nbsp;<strong>&#8220;truco infundado&#8221;<\/strong>&nbsp;basado &#8220;en el descarado deseo de los republicanos extremistas de la C\u00e1mara de abusar de su poder para difamar&#8221; al mandatario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora, los promotores de la investigaci\u00f3n no han aportado pruebas directas de ilegalidades cometidas por Joe Biden. Por otra parte, si la C\u00e1mara, finalmente, vota a favor de la destituci\u00f3n del presidente, es poco probable que esta sea aprobada en el Senado, controlado por los dem\u00f3cratas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los republicanos de la C\u00e1mara de Representantes de EE.UU. planean llevar a cabo este mi\u00e9rcoles una votaci\u00f3n para formalizar su investigaci\u00f3n de&nbsp;juicio pol\u00edtico&nbsp;contra el presidente del pa\u00eds, Joe Biden, reporta&nbsp;Reuters, citando a una fuente an\u00f3nima.&nbsp; Antes de la votaci\u00f3n en el pleno, la resoluci\u00f3n pertinente se presentar\u00e1 este martes ante el Comit\u00e9 de Reglas de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-25027","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/25027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=25027"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/25027\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=25027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=25027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=25027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}