{"id":23507,"date":"2023-11-16T16:17:35","date_gmt":"2023-11-16T20:17:35","guid":{"rendered":"https:\/\/influencias.do\/?p=23507"},"modified":"2023-11-16T16:17:35","modified_gmt":"2023-11-16T20:17:35","slug":"presidenta-parlacen-se-reune-con-secretario-general-del-sica-para-tratar-sobre-participacion-politica-de-la-region","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/11\/16\/presidenta-parlacen-se-reune-con-secretario-general-del-sica-para-tratar-sobre-participacion-politica-de-la-region\/","title":{"rendered":"Presidenta PARLACEN se re\u00fane con Secretario General del SICA para tratar sobre participaci\u00f3n pol\u00edtica de la regi\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta del Parlamento Centroamericano (PARLACEN), la diputada dominicana Silvia Garc\u00eda Polanco, sostuvo una jornada de encuentros en El Salvador con directivos del Sistema de la Integraci\u00f3n Centroamericana (SICA), para el fortalecimiento institucional entre ambos organismos con miras a dinamizar la agenda regional, principalmente&nbsp;sobre la&nbsp;participaci\u00f3n pol\u00edtica en los poderes del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro esa jornada de trabajo, Garc\u00eda Polanco, junto a integrantes de la Comisi\u00f3n de la Mujer, Ni\u00f1ez, Juventud y Familia del PARLACEN, se reuni\u00f3 con el Secretario General del SICA,&nbsp;Werner Isaac Vargas, con quien trataron temas de inter\u00e9s para los pa\u00edses de la regi\u00f3n Centroam\u00e9rica y Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br>Acordaron impulsar una mayor coordinaci\u00f3n entre la Secretar\u00eda General del SICA y el PARLACEN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese encuentro, la presidenta del PARLACEN expuso sobre algunas estrategias a implementar en este \u00f3rgano durante el per\u00edodo de su gesti\u00f3n 2023-2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Tambi\u00e9n particip\u00f3 en la VIII Reuni\u00f3n del Comit\u00e9 Directivo de&nbsp;la Pol\u00edtica Regional de Igualdad y Equidad de G\u00e9nero del Sistema de la Integraci\u00f3n Centroamericana (PRIEG\/SICA), en la que la Secretar\u00eda Ejecutiva de la&nbsp;Coordinaci\u00f3n Educativa y Cultural Centroamericana&nbsp;&nbsp;CECC\/SICA particip\u00f3 en por medio de la Coordinadora Estrat\u00e9gica, Raquel N\u00fa\u00f1ez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se explic\u00f3 que en la reuni\u00f3n, celebrada en la sede de la Secretar\u00eda General del SICA, en San Salvador, se hizo un&nbsp; an\u00e1lisis del estado de avance de la operativizaci\u00f3n de la PRIEG.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su exposici\u00f3n, la presidenta del PARLACEN hizo una&nbsp;presentaci\u00f3n del Plan Sectorial de Igualdad del Eje 6 de la PRIEG\/SICA: \u201cParticipaci\u00f3n Pol\u00edtica en los poderes del Estado 2024-2026\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara el Parlamento Centroamericano una de las luchas actuales que tenemos es la participaci\u00f3n real y protag\u00f3nica&nbsp; de las mujeres en los poderes del estado, pues como sabemos, la igualdad y equidad de g\u00e9nero se considera un elemento fundamental para construir una sociedad justa e inclusiva\u201d, manifest\u00f3 la diputada Silvia Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, explic\u00f3 que la medida 1, orienta a armonizar legislaciones nacionales vinculadas con los derechos pol\u00edticos, para propiciar el incremento de la participaci\u00f3n y representaci\u00f3n pol\u00edtica de las mujeres en su diversidad plural y \u00e9tnica, \u201ctanto&nbsp; en las listas de asamble\u00edstas, \u00f3rganos de direcci\u00f3n y n\u00f3minas de candidaturas a cargos de elecci\u00f3n popular, considerando las particularidades propias del sistema electoral y\/o de los partidos pol\u00edticos de cada pa\u00eds\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esos encuentros&nbsp;tambi\u00e9n particip\u00f3 el titular de la Secretar\u00eda de Integraci\u00f3n Econ\u00f3mica Centroamericana (SIECA), Francisco Lima Mena, y otras personalidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta del Parlamento Centroamericano (PARLACEN), la diputada dominicana Silvia Garc\u00eda Polanco, sostuvo una jornada de encuentros en El Salvador con directivos del Sistema de la Integraci\u00f3n Centroamericana (SICA), para el fortalecimiento institucional entre ambos organismos con miras a dinamizar la agenda regional, principalmente&nbsp;sobre la&nbsp;participaci\u00f3n pol\u00edtica en los poderes del Estado. Dentro esa jornada de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-23507","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/23507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=23507"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/23507\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=23507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=23507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=23507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}