{"id":23147,"date":"2023-11-11T12:34:18","date_gmt":"2023-11-11T16:34:18","guid":{"rendered":"https:\/\/influencias.do\/?p=23147"},"modified":"2023-11-11T12:34:18","modified_gmt":"2023-11-11T16:34:18","slug":"policia-apresa-tres-hombres-acusados-de-homicidio-en-barahona","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/11\/11\/policia-apresa-tres-hombres-acusados-de-homicidio-en-barahona\/","title":{"rendered":"Polic\u00eda apresa tres hombres acusados de homicidio en Barahona"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Miembros del Departamento de Homicidios, pertenecientes a la Direcci\u00f3n Regional Sur, apresaron a tres hombres se\u00f1alados como los responsables de la muerte de una persona en la ciudad de Barahona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de Ricardo Mesa, as\u00ed como los hermanos hermanos Billie Enrique y Manuel Batista Ferrera, a quienes se les atribuye ser los presuntos responsables de la muerte de Eddy Ferreras Medina, de 39 a\u00f1os, a consecuencia de herida por arma de fuego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La v\u00edctima fue encontrada por moradores en unos matorrales en el sector Los Solares de Chava, del distrito municipal de Villa Central, donde resid\u00eda, en un hecho<br>ocurrido el 9 de noviembre del a\u00f1o ecurso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los detenidos ser\u00e1n puestos a disposici\u00f3n del Ministerio P\u00fablico, para los fines legales correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miembros del Departamento de Homicidios, pertenecientes a la Direcci\u00f3n Regional Sur, apresaron a tres hombres se\u00f1alados como los responsables de la muerte de una persona en la ciudad de Barahona. Se trata de Ricardo Mesa, as\u00ed como los hermanos hermanos Billie Enrique y Manuel Batista Ferrera, a quienes se les atribuye ser los presuntos responsables [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-23147","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/23147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=23147"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/23147\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=23147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=23147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=23147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}