{"id":20321,"date":"2023-09-30T10:45:47","date_gmt":"2023-09-30T14:45:47","guid":{"rendered":"https:\/\/influencias.do\/?p=20321"},"modified":"2023-09-30T10:45:47","modified_gmt":"2023-09-30T14:45:47","slug":"nueva-york-amanece-abrumada-tras-inundaciones-historicas-y-se-esperan-mas-lluvias","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/09\/30\/nueva-york-amanece-abrumada-tras-inundaciones-historicas-y-se-esperan-mas-lluvias\/","title":{"rendered":"Nueva York amanece abrumada tras inundaciones hist\u00f3ricas y se esperan m\u00e1s lluvias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Uno de los d\u00edas m\u00e1s lluviosos de Nueva York en d\u00e9cadas\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.telemundo.com\/noticias\/noticias-telemundo\/clima\/urgen-a-permanecer-en-casa-a-los-residentes-de-nueva-york-en-uno-de-lo-rcna118177?cid=linknoticias\" target=\"_blank\">dej\u00f3 el \u00e1rea metropolitana at\u00f3nita y anegada el viernes\u00a0<\/a>despu\u00e9s de que las intensas lluvias interrumpieran el servicio en varias l\u00edneas del subterr\u00e1neo y trenes en los alrededores, conductores quedaran varados en las autopistas, s\u00f3tanos fueran inundados y cerraran durante horas una terminal del Aeropuerto Internacional de La Guardia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al menos unas 8.65 pulgadas (21.97 cent\u00edmetros) de precipitaciones hab\u00edan ca\u00eddo en el Aeropuerto Internacional John F. Kennedy para el anochecer del viernes, superando el r\u00e9cord para cualquier d\u00eda de septiembre, una marca establecida durante el hurac\u00e1n Donna en 1960, inform\u00f3 Servicio Meteorol\u00f3gico Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas zonas de Brooklyn reportaron m\u00e1s de 7.25 pulgadas (18.41 cent\u00edmetros), con al menos un sitio acumulando 2.5 pulgadas (6 cent\u00edmetros) en una hora, seg\u00fan autoridades meteorol\u00f3gicas y municipales. Mientras se espera m\u00e1s lluvia este s\u00e1bado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diluvio ocurri\u00f3 dos a\u00f1os despu\u00e9s de que el hurac\u00e1n Ida trajera precipitaciones r\u00e9cord en el noreste y provocara la muerte de\u00a0<a href=\"https:\/\/apnews.com\/article\/kathy-hochul-lifestyle-travel-floods-d13ad731952cdd33999f9a84ab71dfe0\">13 personas<\/a>\u00a0en la ciudad de Nueva York, principalmente en apartamentos ubicados en s\u00f3tanos que quedaron inundados. Aunque hasta ahora no se han reportado v\u00edctimas mortales ni lesionados, la tormenta del viernes removi\u00f3 recuerdos aterradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades municipales informaron que el viernes recibieron al menos seis reportes de apartamentos en s\u00f3tanos inundados, pero los residentes salieron ilesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gobernadora Kathy Hochul y el alcalde Eric Adams declararon estado de emergencia y\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.telemundo.com\/noticias\/noticias-telemundo\/clima\/urgen-a-permanecer-en-casa-a-los-residentes-de-nueva-york-en-uno-de-lo-rcna118177?a?cid=linknoticias\" target=\"_blank\">pidieron a la poblaci\u00f3n permanecer en casa de ser posible<\/a>, pero las escuelas estaban abiertas y muchos alumnos fueron a clases. Los adultos tuvieron que ir a trabajar, solo para despu\u00e9s hallarse sin saber c\u00f3mo regresar a sus hogares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Casi todas las l\u00edneas del metro estaban o suspendidas, fueron desviadas o retrasadas. El servicio de trenes Metro-North, desde Manhattan, fue suspendido durante gran parte del d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La l\u00ednea de ferrocarril de Long Island qued\u00f3 bloqueada, 44 de los 3,500 autobuses de la ciudad quedaron varados y el servicio de buses se interrumpi\u00f3 en toda la ciudad, se\u00f1alaron las autoridades de tr\u00e1nsito.<em>\u00a0<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando detiene los buses, sabes que es malo\u201d, asegur\u00f3 el estudiante de secundaria en Brooklyn, Malachi Clark, luego de que intent\u00f3 llegar a casa en autob\u00fas, despu\u00e9s en metro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tr\u00e1fico se paraliz\u00f3 a primera hora del d\u00eda en un tramo de la FDR Drive, una de las principales arterias de la zona este de Manhattan. Con el agua por encima de las llantas, algunos conductores abandonaron sus veh\u00edculos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A eso de las 11 de la ma\u00f1ana, Priscilla Fontallio cont\u00f3 que pas\u00f3 tres horas en su auto en una parte de la autopista que no estaba inundada pero donde el tr\u00e1fico no estaba movi\u00e9ndose.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNunca hab\u00eda visto algo as\u00ed en mi vida\u201d, asegur\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente externa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los d\u00edas m\u00e1s lluviosos de Nueva York en d\u00e9cadas\u00a0dej\u00f3 el \u00e1rea metropolitana at\u00f3nita y anegada el viernes\u00a0despu\u00e9s de que las intensas lluvias interrumpieran el servicio en varias l\u00edneas del subterr\u00e1neo y trenes en los alrededores, conductores quedaran varados en las autopistas, s\u00f3tanos fueran inundados y cerraran durante horas una terminal del Aeropuerto Internacional [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[],"class_list":["post-20321","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/20321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=20321"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/20321\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=20321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=20321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=20321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}