{"id":16432,"date":"2023-08-08T15:54:14","date_gmt":"2023-08-08T19:54:14","guid":{"rendered":"https:\/\/influencias.do\/?p=16432"},"modified":"2023-08-08T15:54:14","modified_gmt":"2023-08-08T19:54:14","slug":"aprueban-cambio-de-lema-y-color-del-uniforme-de-la-policia-nacional","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/08\/08\/aprueban-cambio-de-lema-y-color-del-uniforme-de-la-policia-nacional\/","title":{"rendered":"Aprueban cambio de lema y color del uniforme de la Polic\u00eda Nacional"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Consejo Superior Policial aprob\u00f3 los cambios de lema, as\u00ed como tambi\u00e9n los uniformes que usar\u00e1n los agentes de la Polic\u00eda Nacional. De ahora en adelante los uniformados vestir\u00e1n en adelante un color azul, dejando atr\u00e1s el antiguo uniforme gris, mientras que el lema de la instituci\u00f3n ser\u00e1 \u201cProteger y Servir\u201d en vez de \u201cLey y Orden\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n fue ofrecida por el ministro de Interior y Polic\u00eda, Jes\u00fas V\u00e1squez, quien explic\u00f3 que los cambios fueron aprobados por el Consejo Superior Policial y \u201cson parte de la transformaci\u00f3n del cuerpo del orden\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComenzamos el proceso de reforma y transformaci\u00f3n con el ser humano, que ha incluido, adem\u00e1s, la mejora de los cuarteles, del salario, seguro m\u00e9dico, educaci\u00f3n, entre otros beneficios\u201d, seg\u00fan declaraciones del funcionario recogidas en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su llegada al poder, el presidente Luis Abinader anunci\u00f3 y puso en marcha un proceso para la \u201ctransformaci\u00f3n\u201d y \u201cprofesionalizaci\u00f3n\u201d completa de la Polic\u00eda Nacional, un organismo seriamente cuestionado por amplios sectores de la sociedad dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno busc\u00f3 asesor\u00eda de las polic\u00edas de Colombia, Espa\u00f1a, Chile, Israel y Nueva York, entre otros para el proceso de reforma policial. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo Superior Policial aprob\u00f3 los cambios de lema, as\u00ed como tambi\u00e9n los uniformes que usar\u00e1n los agentes de la Polic\u00eda Nacional. De ahora en adelante los uniformados vestir\u00e1n en adelante un color azul, dejando atr\u00e1s el antiguo uniforme gris, mientras que el lema de la instituci\u00f3n ser\u00e1 \u201cProteger y Servir\u201d en vez de \u201cLey [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-16432","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/16432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=16432"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/16432\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=16432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=16432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=16432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}