{"id":152,"date":"2022-10-21T10:08:09","date_gmt":"2022-10-21T14:08:09","guid":{"rendered":"https:\/\/influencias.do\/2022\/10\/21\/igor-rodriguez-prm-ganara-mayoria-posiciones-en-las-proximas-elecciones\/"},"modified":"2022-10-21T10:08:09","modified_gmt":"2022-10-21T14:08:09","slug":"igor-rodriguez-prm-ganara-mayoria-posiciones-en-las-proximas-elecciones","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2022\/10\/21\/igor-rodriguez-prm-ganara-mayoria-posiciones-en-las-proximas-elecciones\/","title":{"rendered":"Igor Rodr\u00edguez: \u201cPRM ganar\u00e1 mayor\u00eda posiciones en las pr\u00f3ximas elecciones\u201d"},"content":{"rendered":"\n<p>Puerto Plata.- El Secretario Nacional de Actas y Correspondencia del Partido Revolucionario Moderno (PRM), Igor Rodr\u00edguez Dur\u00e1n manifest\u00f3 que esa organizaci\u00f3n pol\u00edtica ganar\u00e1 la mayor\u00eda de posiciones electivas en las elecciones que se desarrollar\u00e1n en el 2024.<\/p>\n\n\n\n<p>Rodr\u00edguez, quien tambi\u00e9n se desempe\u00f1a como viceministro Administrativo y Financiero del MAPRE dijo que este triunfo lo encabezar\u00e1 el presidente Luis Abinader por la formidable gesti\u00f3n que ha desarrollado en favor del pueblo dominicano, retornando la institucionalidad, transparencia, solidaridad y sus extensas horas de trabajo en favor del pueblo dominicano.<\/p>\n\n\n\n<p>\u201cEl presidente Luis Abinader fue el primer presidente en asumir en medio del Covid 19, esto represent\u00f3 un gran reto que con \u00e9xitos fue superando, sus decisiones acertadas nos permitieron estar entre los primeros pa\u00edses en superar una enfermedad que provoc\u00f3 la muerte de millones de personas en el mundo\u201d. Dijo Igor<\/p>\n\n\n\n<p>Igor dijo al peri\u00f3dico El Faro que las decisiones tomadas por el presidente Abinader obtuvieron tan buenos resultados que organismos internacionales le reconocieron, por el buen manejo de la salud, turismo y la econom\u00eda.<\/p>\n\n\n\n<p>\u00c9l tambi\u00e9n presidente provincial del PRM en Puerto Plata agreg\u00f3 que en lo municipal y congresual el PRM saldr\u00e1 mucho m\u00e1s fortalecido que en las elecciones del 2020, el extraordinario trabajo que vienen realizando los alcaldes y directores de juntas distritales est\u00e1 generando un alto porcentaje de aceptaci\u00f3n.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que como partido democr\u00e1tico, que abre las puertas a todos los dominicanos y dominicanas de bien, que desean ser parte de los cambios que impulsa ese gobierno que encabeza Abinader, tambi\u00e9n vendr\u00e1n cambios en la conformaci\u00f3n de las boletas, siempre pensando en lo que le convenga al partido y tambi\u00e9n al pa\u00eds, porque no estamos en una organizaci\u00f3n de herencias, todo el que entienda que tiene los m\u00e9ritos, el recorrido y los buenos deseos de aportar, tendr\u00e1n la oportunidad de presentar sus propuestas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Plata.- El Secretario Nacional de Actas y Correspondencia del Partido Revolucionario Moderno (PRM), Igor Rodr\u00edguez Dur\u00e1n manifest\u00f3 que esa organizaci\u00f3n pol\u00edtica ganar\u00e1 la mayor\u00eda de posiciones electivas en las elecciones que se desarrollar\u00e1n en el 2024. Rodr\u00edguez, quien tambi\u00e9n se desempe\u00f1a como viceministro Administrativo y Financiero del MAPRE dijo que este triunfo lo encabezar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[106],"tags":[214,180,215],"class_list":{"0":"post-152","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"tag-igor-rodriguez","9":"tag-politica","10":"tag-prm"},"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}