{"id":14686,"date":"2023-07-19T10:58:07","date_gmt":"2023-07-19T14:58:07","guid":{"rendered":"https:\/\/influencias.do\/?p=14686"},"modified":"2023-07-19T10:58:07","modified_gmt":"2023-07-19T14:58:07","slug":"voleibol-rd-debuta-con-victoria-frente-a-canada-en-la-copa-panam-sub-23","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/07\/19\/voleibol-rd-debuta-con-victoria-frente-a-canada-en-la-copa-panam-sub-23\/","title":{"rendered":"Voleibol RD debuta con victoria frente a Canad\u00e1 en la Copa Panam Sub 23"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las campeonas defensoras de Rep\u00fablica Dominicana vencieron este martes a Canad\u00e1 3-0 (26-24, 25-18, 25-15) en su debut en la Copa Panamericana de Voleibol Femenino Sub 23, que se celebra en la Arena Sonora de Hermosillo, M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fiesta de puntos en el primer set estuvo empatada en numerosas ocasiones, alcanzando a empatar al punto 23 cuando Canad\u00e1 le arrebat\u00f3 un punto de set antes de que las Dominicanas terminaran arriba 26-24. Rep\u00fablica Dominicana entr\u00f3 con mayor potencia para terminar con c\u00f3modas ventajas los siguientes dos sets.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los elementos de juego estuvieron balanceados, con Rep\u00fablica Dominicana encabezando 37 a 31 en ataques, 8 a 6 en bloqueos y 7 a 4 en puntos de servicios. Las Dominicanas anotaron 24 puntos de errores canadienses y cometieron 16.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tres dominicanas anotaron d\u00edgitos dobles, encabezadas por la jugadora de esquina Madeline Guill\u00e9n con 14 puntos (9 ataques, 2 bloqueos, 2 aces), Flormarie Heredia con 12 puntos (10 ataques, un bloqueo, un ace) y Alondra Tapia con 10 puntos (9 ataques, un bloqueo).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por Canad\u00e1, Raya Surinx y Jasmine Rivest lideraron con 11 y 10 puntos respectivamente. La capitana, Lucy Borrowski agreg\u00f3 7 puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Juegos de hoy<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este mi\u00e9rcoles Rep\u00fablica Dominicana (1-0) se enfrentar\u00e1 a Per\u00fa (1-0), en tanto que Canad\u00e1 (0-1) va ante Cuba (0-1). &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Camila de la Rosa, capitana dominicana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dominicana:&nbsp;<\/strong>\u201cDesconoc\u00edamos a las jugadoras de Canad\u00e1 y a su manera de jugar. Hicimos un buen trabajo en analizar lo que ellas estaban haciendo, as\u00ed manejamos el partido para ganarlo. Considero que nuestro bloqueo fue muy importante para victoria\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lucy Borrowski, capitana de Canad\u00e1:&nbsp;<\/strong>\u201cEntramos fuerte. Rep\u00fablica Dominicana es un equipo dif\u00edcil y se nos cay\u00f3 un poco nuestra lucha, lo est\u00e1bamos jugando inteligentes y creo que podremos salir m\u00e1s fuertes ma\u00f1ana\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wagner Pacheco, entrenador de Rep\u00fablica Dominicana:&nbsp;<\/strong>\u201cPienso que el primer set fue muy disputado porque no conoc\u00eda al equipo de Canad\u00e1, salimos a ciegas. Despu\u00e9s del primer set jugamos muy bien, el saque fue potente y el contraataque. Lo bueno fue que aprendimos r\u00e1pido para enfrentar a Canad\u00e1 y eso nos facilit\u00f3 las cosas. Fallamos algunas cosas que son normales en un estreno.\u201d &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carolyn O\u2019Dwyer, entrenadora de Canad\u00e1:\u00a0<\/strong>\u201cSalimos con fuerza, pero batallamos un poco con el primer contacto del bal\u00f3n y cometiendo demasiados errores. Con un nuevo equipo vamos a mejorar y mejorar. Definitivamente hay espacio para mejorar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las campeonas defensoras de Rep\u00fablica Dominicana vencieron este martes a Canad\u00e1 3-0 (26-24, 25-18, 25-15) en su debut en la Copa Panamericana de Voleibol Femenino Sub 23, que se celebra en la Arena Sonora de Hermosillo, M\u00e9xico. La fiesta de puntos en el primer set estuvo empatada en numerosas ocasiones, alcanzando a empatar al punto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[123],"tags":[],"class_list":["post-14686","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/14686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=14686"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/14686\/revisions"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=14686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=14686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=14686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}