{"id":11122,"date":"2023-05-31T10:16:23","date_gmt":"2023-05-31T14:16:23","guid":{"rendered":"https:\/\/influencias.do\/?p=11122"},"modified":"2023-05-31T10:16:23","modified_gmt":"2023-05-31T14:16:23","slug":"twitter-solo-vale-un-tercio-de-los-44-000-millones-de-dolares-que-pago-elon-musk","status":"publish","type":"post","link":"https:\/\/influencias.do\/index.php\/2023\/05\/31\/twitter-solo-vale-un-tercio-de-los-44-000-millones-de-dolares-que-pago-elon-musk\/","title":{"rendered":"Twitter solo vale un tercio de los 44.000 millones de d\u00f3lares que pag\u00f3 Elon Musk"},"content":{"rendered":"\n<p>Twitter vale actualmente apenas un tercio de los 44.000 millones de d\u00f3lares que pag\u00f3 Elon Musk cuando&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/446225-reportar-elon-musk-encargar-direccion-twitter\" target=\"_blank\" rel=\"noreferrer noopener\">adquiri\u00f3<\/a>&nbsp;la compa\u00f1\u00eda en octubre de 2022, asegura Bloomberg, con base en una valoraci\u00f3n de cartera revelada por la financiera estadounidense Fidelity Investments, que redujo el valor de su participaci\u00f3n accionaria.<\/p>\n\n\n\n<p>En marzo pasado, Musk hab\u00eda\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/actualidad.rt.com\/actualidad\/462004-musk-valora-twitter-20000-millones-dolares\" target=\"_blank\">valorado<\/a>\u00a0la red social en 20.000 millones de d\u00f3lares. Sin embargo, Fidelity, que respald\u00f3 con capital la compra de la red social, disminuy\u00f3 de nuevo su participaci\u00f3n en la empresa, que para abril se situ\u00f3 en 6,55 millones de d\u00f3lares, seg\u00fan\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.actionsxchangerepository.fidelity.com\/ShowDocument\/ComplianceEnvelope.htm?_fax=-5%23-96%23-92%23-102%23-55%23121%23-88%23-81%23105%236%2313%23-58%23-58%2376%2369%23-124%23105%23111%23-35%2375%23-100%23-43%23-71%23-35%2378%23-86%23-90%2389%23-118%2371%23-50%2325%23-109%23-22%2337%23-126%2341%23112%23118%23100%2393%23113%23-112%23127%23-42%23-97%2330%23-58%23-29%23102%23-60%23-47%239%23-82%23100%2349%23-115%23-125%2329%23-69%23126%23-16%23-72%23-50%23-75%23-54%2324%2343%23-48%23-44%2368%234%2311%23123%2334%2333%2396%23-121%23-65%2340%23-23%2373%23117%23-106%2347%2332%23-88%2321%23\" target=\"_blank\">datos<\/a>\u00a0divulgados el 28 de mayo.<\/p>\n\n\n\n<p>En este contexto,&nbsp;Bloomberg deduce que el valor de Twitter&nbsp;ronda los 15.000 millones de d\u00f3lares y&nbsp;<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2023-05-30\/twitter-is-worth-33-of-musk-s-purchase-price-fidelity-says\" target=\"_blank\" rel=\"noreferrer noopener\">se\u00f1ala<\/a>&nbsp;que no est\u00e1 claro c\u00f3mo ha llegado Fidelity a su nueva valoraci\u00f3n ni si recibe informaci\u00f3n no p\u00fablica de la empresa.<\/p>\n\n\n\n<p>D\u00edas despu\u00e9s de que Musk cerrara el trato de compra de la plataforma de microblogueo, la participaci\u00f3n de Fidelity estaba valorada en casi 20 millones de d\u00f3lares. En noviembre,&nbsp;<a href=\"https:\/\/www.reuters.com\/technology\/fidelity-marks-down-value-twitter-stake-by-56-2022-12-30\/\" target=\"_blank\" rel=\"noreferrer noopener\">baj\u00f3<\/a>&nbsp;en un 56 %, a 8,63 millones de d\u00f3lares. Seg\u00fan la revista&nbsp;<a href=\"https:\/\/www.forbes.com\/sites\/antoniopequenoiv\/2023\/05\/30\/fidelity-values-twitter-at-roughly-15-billion-a-third-of-the-sticker-price-paid-by-musk\/?sh=5a3002613e7d\" target=\"_blank\" rel=\"noreferrer noopener\">Forbes<\/a>, al mes siguiente se redujo en otro 9,6 %.<\/p>\n\n\n\n<p>Seg\u00fan el \u00edndice de multimillonarios de Bloomberg, basado en la valoraci\u00f3n de Fidelity, la inversi\u00f3n de Musk en Twitter ahora vale 8.800 millones de d\u00f3lares, quien gast\u00f3 m\u00e1s de 25.000 millones de d\u00f3lares para adquirir una participaci\u00f3n del 79 % de la compa\u00f1\u00eda el a\u00f1o pasado. Si bien esto se traduce en p\u00e9rdidas cercanas a los 850 millones para el magnate, su fortuna ha subido m\u00e1s de 48.000 millones de d\u00f3lares este a\u00f1o, en gran parte por el incremento en un 63 % del precio de las acciones de Tesla Inc. RT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Twitter vale actualmente apenas un tercio de los 44.000 millones de d\u00f3lares que pag\u00f3 Elon Musk cuando&nbsp;adquiri\u00f3&nbsp;la compa\u00f1\u00eda en octubre de 2022, asegura Bloomberg, con base en una valoraci\u00f3n de cartera revelada por la financiera estadounidense Fidelity Investments, que redujo el valor de su participaci\u00f3n accionaria. En marzo pasado, Musk hab\u00eda\u00a0valorado\u00a0la red social en 20.000 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"content-type":"","iawp_total_views":0,"footnotes":""},"categories":[109],"tags":[360,363],"class_list":{"0":"post-11122","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacionales","8":"tag-elon-musk","9":"tag-twitter"},"_links":{"self":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/11122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/comments?post=11122"}],"version-history":[{"count":0,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/posts\/11122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/media?parent=11122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/categories?post=11122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influencias.do\/index.php\/wp-json\/wp\/v2\/tags?post=11122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}